{"id":98367,"date":"2023-01-29T20:06:02","date_gmt":"2023-01-29T21:06:02","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=98367"},"modified":"2023-01-29T20:06:02","modified_gmt":"2023-01-29T21:06:02","slug":"%d8%a8%d8%a7%d9%86%da%a9-%d8%b5%d8%a7%d8%af%d8%b1%d8%a7%d8%aa-%d8%a7%db%8c%d8%b1%d8%a7%d9%86-%d9%a2%d9%a1%d9%a8-%d9%87%d8%b2%d8%a7%d8%b1-%d9%85%db%8c%d9%84%db%8c%d8%a7%d8%b1%d8%af-%d8%b1%db%8c%d8%a7-2","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/98367","title":{"rendered":"\u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646 \u0662\u0661\u0668 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0648\u0627\u0645 \u0642\u0631\u0636\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0648 \u062d\u0645\u0627\u06cc\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0631\u062f"},"content":{"rendered":"<p>\n\u062a\u0639\u062f\u0627\u062f \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0642\u0631\u0636\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0648 \u062d\u0645\u0627\u06cc\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u0634\u062f\u0647 \u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u0641\u0631\u0648\u0631\u062f\u06cc\u0646 \u062a\u0627 \u0646\u06cc\u0645\u0647 \u062f\u06cc \u0645\u0627\u0647 \u0633\u0627\u0644 \u0661\u0664\u0660\u0661 \u0628\u0647 \u0662\u0663\u0665 \u0647\u0632\u0627\u0631 \u0641\u0642\u0631\u0647 \u0628\u0647 \u0627\u0631\u0632\u0634 \u0628\u0627\u0644\u063a \u0628\u0631 \u0662\u0661\u0668 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0631\u0633\u06cc\u062f.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc  \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637\u200c\u0639\u0645\u0648\u0645\u06cc \u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646\u060c \u067e\u0631\u062f\u0627\u062e\u062a \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062d\u0645\u0627\u06cc\u062a\u06cc \u0627\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u062a\u062d\u0642\u0642 \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u0642\u0627\u0648\u0645\u062a\u06cc\u060c \u0628\u0647\u0628\u0648\u062f \u0645\u0639\u06cc\u0634\u062a \u0645\u0631\u062f\u0645 \u0627\u0642\u0635\u06cc \u0646\u0642\u0627\u0637 \u06a9\u0634\u0648\u0631\u060c \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0631\u0648\u0646\u0642 \u062a\u0648\u0644\u06cc\u062f \u062f\u0631 \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u062e\u0631\u062f \u0648 \u06a9\u0644\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0639\u0645\u0644 \u0628\u0647 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062f\u0631 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062d\u0645\u0627\u06cc\u062a\u06cc\u060c \u062f\u0631 \u0633\u0627\u0644 \u0661\u06f4\u0660\u0661 \u0646\u06cc\u0632 \u0627\u062f\u0627\u0645\u0647 \u06cc\u0627\u0641\u062a\u0647 \u0628\u0647 \u0646\u062d\u0648\u06cc \u06a9\u0647 \u062a\u0627 \u0646\u06cc\u0645\u0647 \u062f\u06cc \u0645\u0627\u0647 \u0633\u0627\u0644 \u062c\u0627\u0631\u06cc \u0662\u0661\u0668 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0628\u0631\u0627\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u062d\u062f\u0648\u062f \u0662\u0663\u06f5 \u0647\u0632\u0627\u0631 \u0641\u0642\u0631\u0647 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0642\u0631\u0636\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0648 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062d\u0645\u0627\u06cc\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u0634\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u062f\u062a \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u0661\u0668\u0660 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u0642\u0631\u0636\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0628\u0647 \u0662\u0660\u0668 \u0647\u0632\u0627\u0631 \u0646\u0641\u0631 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0627\u0632\u062f\u0648\u0627\u062c \u0648 \u062a\u0647\u06cc\u0647 \u062c\u0647\u06cc\u0632\u06cc\u0647\u060c \u0627\u0634\u062a\u063a\u0627\u0644\u0632\u0627\u06cc\u06cc \u06a9\u0645\u06cc\u062a\u0647 \u0627\u0645\u062f\u0627\u062f\u060c \u0633\u0627\u0632\u0645\u0627\u0646 \u0628\u0647\u0632\u06cc\u0633\u062a\u06cc\u060c \u0628\u0646\u06cc\u0627\u062f \u0628\u0631\u06a9\u062a\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u06cc\u200c\u0647\u0627\u060c \u0627\u0639\u0637\u0627\u06cc \u0648\u0627\u0645 \u0641\u0631\u0632\u0646\u062f\u0622\u0648\u0631\u06cc\u060c \u0648\u062f\u06cc\u0639\u0647 \u0645\u0633\u06a9\u0646 \u0645\u062f\u062f\u062c\u0648\u06cc\u0627\u0646 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062d\u0645\u0627\u06cc\u062a\u06cc\u060c \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0636\u0631\u0648\u0631\u06cc \u0633\u062a\u0627\u062f \u062f\u06cc\u0647 \u0648 \u0627\u0634\u062a\u063a\u0627\u0644 \u0632\u0646\u062f\u0627\u0646\u06cc\u0627\u0646\u060c \u0648\u0627\u0645 \u0636\u0631\u0648\u0631\u06cc\u060c \u062f\u0631\u0645\u0627\u0646 \u0648 \u062d\u0645\u0627\u0645 \u0631\u0648\u0633\u062a\u0627\u06cc\u06cc \u0633\u0647\u0645 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u062f\u0631 \u062a\u0627\u0645\u06cc\u0646 \u0646\u06cc\u0627\u0632 \u0645\u0631\u062f\u0645 \u06a9\u0634\u0648\u0631 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a.<br \/>\n\u0647\u0645\u0686\u0646\u06cc\u0646 \u067e\u0631\u062f\u0627\u062e\u062a \u0628\u06cc\u0634 \u0627\u0632 \u0662\u06f6 \u0647\u0632\u0627\u0631 \u0648 \u0668\u0660\u0660 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u0648\u062f\u06cc\u0639\u0647 \u0645\u0633\u06a9\u0646 (\u0627\u0642\u062f\u0627\u0645 \u0645\u0644\u06cc \u0645\u0633\u06a9\u0646)\u060c \u0648\u0627\u0645 \u0645\u0633\u06a9\u0646 \u0627\u06cc\u062b\u0627\u0631\u06af\u0631\u0627\u0646 \u0648 \u0631\u0632\u0645\u0646\u062f\u06af\u0627\u0646\u060c \u0646\u0648\u0633\u0627\u0632\u06cc \u0648 \u0628\u0647\u0633\u0627\u0632\u06cc \u0645\u0633\u06a9\u0646 \u0631\u0648\u0633\u062a\u0627\u06cc\u06cc\u060c \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u062a\u0639\u0627\u0648\u0646 \u0631\u0648\u0633\u062a\u0627\u06cc\u06cc\u060c \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631\u0628\u0646\u0627\u06cc\u06cc \u0645\u0627\u062f\u0647 \u06f5\u06f6 \u0648 \u062a\u0623\u0645\u06cc\u0646 \u0648 \u062a\u0648\u0644\u06cc\u062f \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0627\u0633\u0627\u0633\u06cc \u0628\u0647 \u0627\u0631\u0632\u0634 \u0628\u0627\u0644\u063a \u0628\u0631 \u0663\u0668 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0627\u0632 \u062f\u06cc\u06af\u0631 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u062d\u0645\u0627\u06cc\u062a\u06cc \u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646 \u0628\u0631\u0627\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0641\u0631\u0648\u0631\u062f\u06cc\u0646 \u062a\u0627 \u0646\u06cc\u0645\u0647 \u062f\u06cc \u0645\u0627\u0647 \u0633\u0627\u0644 \u062c\u0627\u0631\u06cc \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0639\u062f\u0627\u062f \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0642\u0631\u0636\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0648 \u062d\u0645\u0627\u06cc\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u0634\u062f\u0647 \u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u0641\u0631\u0648\u0631\u062f\u06cc\u0646 \u062a\u0627 \u0646\u06cc\u0645\u0647 \u062f\u06cc \u0645\u0627\u0647 \u0633\u0627\u0644 \u0661\u0664\u0660\u0661 \u0628\u0647 \u0662\u0663\u0665 \u0647\u0632\u0627\u0631 \u0641\u0642\u0631\u0647 \u0628\u0647 \u0627\u0631\u0632\u0634 \u0628\u0627\u0644\u063a \u0628\u0631 \u0662\u0661\u0668 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0631\u0633\u06cc\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637\u200c\u0639\u0645\u0648\u0645\u06cc \u0628\u0627\u0646\u06a9 \u0635\u0627\u062f\u0631\u0627\u062a \u0627\u06cc\u0631\u0627\u0646\u060c \u067e\u0631\u062f\u0627\u062e\u062a \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062d\u0645\u0627\u06cc\u062a\u06cc \u0627\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0647 \u062a\u062d\u0642\u0642 \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u0642\u0627\u0648\u0645\u062a\u06cc\u060c \u0628\u0647\u0628\u0648\u062f \u0645\u0639\u06cc\u0634\u062a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":98368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-98367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/98367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=98367"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/98367\/revisions"}],"predecessor-version":[{"id":98369,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/98367\/revisions\/98369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/98368"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=98367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=98367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=98367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}