{"id":96768,"date":"2023-01-11T22:30:23","date_gmt":"2023-01-11T23:30:23","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=96768"},"modified":"2023-01-11T22:30:23","modified_gmt":"2023-01-11T23:30:23","slug":"%d8%a8%d8%b1%d8%b1%d8%b3%db%8c-%d8%a8%d8%a7%d8%b2%d8%af%d9%87%db%8c-%d8%b3%d9%87%d8%a7%d9%85-%d8%b4%da%af%d9%88%db%8c%d8%a7-%d9%88-%da%86%d8%b4%d9%85-%d8%a7%d9%86%d8%af%d8%a7%d8%b2-%d8%a2%db%8c%d9%86","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/96768","title":{"rendered":"\u0628\u0631\u0631\u0633\u06cc \u0628\u0627\u0632\u062f\u0647\u06cc \u0633\u0647\u0627\u0645 \u0634\u06af\u0648\u06cc\u0627 \u0648 \u0686\u0634\u0645 \u0627\u0646\u062f\u0627\u0632 \u0622\u06cc\u0646\u062f\u0647 \u0633\u0648\u062f \u0628\u0627\u0644\u0627\u062a\u0631 \u0627\u0632 \u06f3\u06f1 \u062f\u0631\u0635\u062f \u062f\u0631 \u06cc\u06a9 \u0645\u0627\u0647 \u0628\u0631\u0627\u06cc \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0634\u0647\u06cc\u062f \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646\/ \u0631\u0634\u062f \u06f1\u06f9 \u062f\u0631\u0635\u062f\u06cc \u0641\u0631\u0648\u0634"},"content":{"rendered":"<p>\n\u0633\u0647\u0627\u0645 \u0634\u0631\u06a9\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0634\u0647\u06cc\u062f \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646 (\u0634\u06af\u0648\u06cc\u0627) \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0627 \u0628\u0627\u0632\u062f\u0647\u06cc 31.6 \u062f\u0631\u0635\u062f \u0638\u0631\u0641 \u06cc\u06a9 \u0645\u0627\u0647 \u0627\u062e\u06cc\u0631 \u0631\u06a9\u0648\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u062e\u0648\u062f \u0628\u0647 \u062c\u0627\u06cc \u06af\u0630\u0627\u0634\u062a.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u060c\u0628\u0631\u0631\u0633\u06cc \u0631\u0648\u0646\u062f \u0642\u06cc\u0645\u062a \u0633\u0647\u0627\u0645 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646 \u0637\u06cc \u06cc\u06a9 \u0645\u0627\u0647 \u0627\u062e\u06cc\u0631 (\u06f2\u06f0 \u0622\u0630\u0631 \u2013 \u06f2\u06f0 \u062f\u06cc \u0645\u0627\u0647) \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0642\u06cc\u0645\u062a \u0627\u06cc\u0646 \u0633\u0647\u0645 \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u0627\u0632 \u06f9\u06f4\u06f2\u06f0 \u0631\u06cc\u0627\u0644 \u062f\u0631 \u06f2\u06f0 \u0622\u0630\u0631\u0645\u0627\u0647 \u0628\u0647 \u06f1\u06f2\u060c\u06f3\u06f0\u06f0 \u0631\u06cc\u0627\u0644 \u062f\u0631 \u067e\u0627\u06cc\u0627\u0646 \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u06f2\u06f0 \u062f\u06cc \u0645\u0627\u0647 \u0631\u0633\u06cc\u062f\u0647 \u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u062a\u0648\u0627\u0646\u0633\u062a\u0647\u200c\u0627\u0646\u062f \u06f3\u06f1\u066b\u06f6 \u062f\u0631\u0635\u062f \u0633\u0648\u062f \u06a9\u0633\u0628 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a \u0627\u062f\u0627\u0645\u0647 \u0648\u0636\u0639\u06cc\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0647 \u0645\u0627\u0647 \u06af\u0630\u0634\u062a\u0647 \u0634\u06a9\u0644 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0627\u06cc\u0646 \u0628\u0631\u0631\u0633\u06cc \u0631\u0627 \u0628\u0647 \u0645\u062d\u062f\u0648\u062f\u0647 \u0632\u0645\u0627\u0646\u06cc \u0633\u0647 \u0645\u0627\u0647\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u0645 \u0628\u0627\u0632 \u0647\u0645 \u0634\u0627\u0647\u062f \u0628\u0627\u0632\u062f\u0647\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u06f3\u06f9\u066b\u06f8 \u062f\u0631\u0635\u062f\u06cc \u0637\u06cc \u0633\u0647 \u0645\u0627\u0647 \u06af\u0630\u0634\u062a\u0647 \u0647\u0633\u062a\u06cc\u0645.<br \/>\n\u0627\u06cc\u0646 \u0628\u0627\u0632\u062f\u0647\u06cc \u0641\u0642\u0637 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a \u0627\u06cc\u0646 \u0633\u0647\u0645 \u0627\u0633\u062a \u0648 \u0628\u062e\u0634 \u062f\u06cc\u06af\u0631\u06cc \u0627\u0632 \u0633\u0648\u062f \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0633\u0648\u062f \u062a\u0642\u0633\u06cc\u0645\u06cc \u0634\u0631\u06a9\u062a \u0637\u06cc \u06cc\u06a9 \u0633\u0627\u0644 \u0627\u0633\u062a.<br \/>\n\u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0645\u062c\u0645\u0639 \u0639\u0645\u0648\u0645\u06cc \u0633\u0627\u0644\u06cc\u0627\u0646\u0647\u060c \u0633\u0647\u0645\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0646\u06af\u0627\u0647 \u062f\u0627\u0634\u062a\u0647\u200c\u0627\u0646\u062f \u0633\u0648\u062f \u062a\u0642\u0633\u06cc\u0645\u06cc \u0633\u0627\u0644\u06cc\u0627\u0646\u0647 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0647 \u0637\u0648\u0631 \u0646\u0642\u062f\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0628\u0644\u063a \u0628\u0631\u0627\u06cc \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u06f1\u060c\u06f2\u06f5\u06f0 \u0631\u06cc\u0627\u0644 \u0628\u0647 \u0627\u0632\u0627\u06cc \u0647\u0631 \u0633\u0647\u0645 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u062e\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u06af\u0630\u0634\u062a\u0647 \u062f\u0631\u0628\u0627\u0631\u0647 \u0622\u0646 \u062a\u0635\u0645\u06cc\u0645 \u06af\u06cc\u0631\u06cc \u0634\u062f \u0648 \u0628\u0647 \u0637\u0648\u0631 \u0646\u0642\u062f\u06cc \u0628\u0647 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u067e\u0631\u062f\u0627\u062e\u062a \u0634\u062f.<br \/>\n\u0628\u0631 \u0627\u0633\u0627\u0633 \u067e\u06cc\u0634 \u0628\u06cc\u0646\u06cc \u0627\u0645\u0633\u0627\u0644 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a\u060c \u0637\u06cc \u0633\u0627\u0644 \u0645\u0627\u0644\u06cc \u062c\u0627\u0631\u06cc \u0647\u0631 \u0633\u0647\u0645 \u0634\u0631\u06a9\u062a \u0645\u0628\u0644\u063a\u06f1\u060c\u06f3\u06f9\u06f0 \u0631\u06cc\u0627\u0644 \u0633\u0648\u062f \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a \u06a9\u0647 \u0627\u06af\u0631 \u0627\u06cc\u0646 \u0645\u0628\u0644\u063a \u0631\u0627 \u0628\u0647 \u0633\u0648\u062f \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0627\u0636\u0627\u0641\u0647 \u06a9\u0646\u06cc\u0645 \u0633\u0648\u062f \u0645\u0627\u0647 \u062c\u0627\u0631\u06cc \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0628\u0631\u0627\u06cc \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u0628\u0627 \u062f\u06cc\u062f \u062f\u0631\u0627\u0632\u0645\u062f\u062a \u0628\u06cc\u0634 \u0627\u0632 \u06f2\u06f0 \u062f\u0631\u0635\u062f \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<br \/>\n\u0646\u06a9\u062a\u0647 \u062f\u06cc\u06af\u0631 \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u0631\u0632\u0634 \u0627\u06cc\u0646 \u0633\u0647\u0645\u060c \u06af\u0632\u0627\u0631\u0634 \u0645\u0627\u0644\u06cc \u0622\u0630\u0631\u0645\u0627\u0647 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0645\u062c\u0645\u0648\u0639 \u0641\u0631\u0648\u0634 \u0633\u0647 \u0645\u0627\u0647\u0647 \u067e\u0627\u06cc\u06cc\u0632 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f1 \u0628\u0647 \u0645\u0628\u0644\u063a \u06f5\u06f0\u06f8\u06f6 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646 \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646 \u0648\u0635\u0641\u060c \u0641\u0631\u0648\u0634 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0635\u0644\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u062f\u062a \u0645\u0634\u0627\u0628\u0647 \u0633\u0627\u0644 \u0642\u0628\u0644 \u0631\u0634\u062f \u06f1\u06f9 \u062f\u0631\u0635\u062f\u06cc \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u067e\u06cc\u0634 \u0628\u06cc\u0646\u06cc\u200c\u0647\u0627\u0633\u062a.<br \/>\n\u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0646\u0647 \u0645\u0627\u0647\u0647 \u0646\u062e\u0633\u062a \u0641\u0639\u0627\u0644\u06cc\u062a \u062e\u0648\u062f \u062f\u0631 \u0633\u0627\u0644 \u0645\u0627\u0644\u06cc \u06f1\u06f4\u06f0\u06f1 \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u06f7\u06f3 \u062f\u0631\u0635\u062f \u0627\u0632 \u0628\u0648\u062f\u062c\u0647 \u0641\u0631\u0648\u0634 \u0633\u0627\u0644\u0627\u0646\u0647 \u062e\u0648\u062f \u0631\u0627 \u067e\u0648\u0634\u0634 \u062f\u0647\u062f. \u0627\u06cc\u0646 \u0646\u06a9\u0627\u062a \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u06a9\u0647 \u0641\u0639\u0627\u0644\u0627\u0646 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc \u0628\u0648\u0631\u0633\u060c \u0686\u0634\u0645 \u0627\u0646\u062f\u0627\u0632 \u0631\u0648\u0634\u0646 \u0648 \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0633\u0647\u0645 \u0642\u0627\u0626\u0644 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0631 \u0627\u06cc\u0646 \u0627\u0633\u0627\u0633 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u067e\u06cc\u0634 \u0628\u06cc\u0646\u06cc \u0627\u0642\u0628\u0627\u0644 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0647\u0645 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a \u0622\u0646 \u0631\u0627 \u062f\u0627\u0634\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u0647\u0627\u0645 \u0634\u0631\u06a9\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0634\u0647\u06cc\u062f \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646 (\u0634\u06af\u0648\u06cc\u0627) \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0627 \u0628\u0627\u0632\u062f\u0647\u06cc 31.6 \u062f\u0631\u0635\u062f \u0638\u0631\u0641 \u06cc\u06a9 \u0645\u0627\u0647 \u0627\u062e\u06cc\u0631 \u0631\u06a9\u0648\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u062e\u0648\u062f \u0628\u0647 \u062c\u0627\u06cc \u06af\u0630\u0627\u0634\u062a. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u060c\u0628\u0631\u0631\u0633\u06cc \u0631\u0648\u0646\u062f \u0642\u06cc\u0645\u062a \u0633\u0647\u0627\u0645 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062a\u0646\u062f\u06af\u0648\u06cc\u0627\u0646 \u0637\u06cc \u06cc\u06a9 \u0645\u0627\u0647 \u0627\u062e\u06cc\u0631 (\u06f2\u06f0 \u0622\u0630\u0631 \u2013 \u06f2\u06f0 \u062f\u06cc \u0645\u0627\u0647) \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":96769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-96768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/96768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=96768"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/96768\/revisions"}],"predecessor-version":[{"id":96770,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/96768\/revisions\/96770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/96769"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=96768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=96768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=96768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}