{"id":81713,"date":"2022-06-22T21:15:53","date_gmt":"2022-06-22T21:15:53","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=81713"},"modified":"2022-06-22T21:15:53","modified_gmt":"2022-06-22T21:15:53","slug":"%d9%85%d9%82%d8%a7%db%8c%d8%b3%d9%87-%d8%b9%d9%85%d9%84%da%a9%d8%b1%d8%af-%d9%a3%d9%85%d8%a7%d9%87%d9%87-%d8%b5%d9%86%d8%a7%db%8c%d8%b9-%d8%b4%db%8c%d8%b1%d8%a7%db%8c%d8%b1%d8%a7%d9%86-%d8%a8%d8%a7","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/81713","title":{"rendered":"\u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0663\u0645\u0627\u0647\u0647 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0631\u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0633\u0627\u0644 \u0642\u0628\u0644 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f:   \u0631\u0634\u062f \u0661\u06f5\u0663 \u062f\u0631\u0635\u062f\u06cc \u0633\u0648\u062f \u0648 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u067e\u06af\u0627\u0647 \u062f\u0631 \u0633\u0627\u0644 \u0661\u06f4\u0660\u0661"},"content":{"rendered":"\n<p> \u0628\u0631\u0631\u0633\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0631\u0627\u06cc\u0631\u0627\u0646 (\u067e\u06af\u0627\u0647) \u062f\u0631 \u0628\u0647\u0627\u0631 \u0661\u06f4\u0660\u0661 \u0627\u0632 \u0631\u0634\u062f \u062f\u0633\u062a\u0647 \u062c\u0645\u0639\u06cc \u0634\u0627\u062e\u0635\u200c\u0647\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a\u06cc \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062d\u06a9\u0627\u06cc\u062a \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632  \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0648 \u0627\u0645\u0648\u0631 \u0628\u064a\u0646 \u0627\u0644\u0645\u0644\u0644 \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0631 \u0627\u06cc\u0631\u0627\u0646 (\u067e\u06af\u0627\u0647)\u060c \u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0663 \u0645\u0627\u0647\u0647 \u0646\u062e\u0633\u062a \u0633\u0627\u0644 \u0661\u06f4\u0660\u0661 \u0628\u0647 \u0628\u0647\u0627\u0631 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u062e\u0628\u0631 \u0627\u0632 \u062a\u062d\u0642\u0642 \u0633\u0648\u062f \u0661\u06f5\u0663 \u062f\u0631\u0635\u062f\u06cc\u060c \u062f\u0631\u067e\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u0634\u062f \u06f6\u0660 \u062f\u0631\u0635\u062f\u06cc \u0641\u0631\u0648\u0634 \u0631\u06cc\u0627\u0644\u06cc \u0635\u0627\u062f\u0631\u0627\u062a \u0648 \u0631\u0634\u062f \u06f6\u0663 \u062f\u0631\u0635\u062f\u06cc \u0641\u0631\u0648\u0634 \u0631\u06cc\u0627\u0644\u06cc \u062f\u0627\u062e\u0644\u06cc \u062f\u0631 \u0628\u0647\u0627\u0631 \u0661\u06f4\u0660\u0661 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<p>\u0628\u0631\u0631\u0633\u06cc \u062f\u0627\u062f\u0647 \u0647\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0631\u06cc\u0644\u200c\u06af\u0630\u0627\u0631\u06cc \u0634\u0631\u06a9\u062a \u0628\u0627\u0639\u062b \u0627\u0631\u062a\u0642\u0627\u06cc \u0668\u0668 \u062f\u0631\u0635\u062f\u06cc \u0627\u0631\u0632\u0634 \u0633\u0628\u062f \u0641\u0631\u0648\u0634 \u0634\u062f\u0647  \u06a9\u0647 \u062d\u0627\u06a9\u06cc \u0627\u0632 \u00ab\u0628\u0647\u0628\u0648\u062f \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0647\u06cc\u0646\u0647 \u062a\u0648\u0644\u06cc\u062f \u0648\u0641\u0631\u0648\u0634\u00bb \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0631\u067e\u0627\u06cc\u0647 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634\u060c \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc \u0641\u0631\u0648\u0634 \u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0631\u0648\u06cc\u0647\u200c \u062f\u0631\u0645\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u0628\u062a\u062f\u0627\u06cc\u06cc \u0627\u0645\u0633\u0627\u0644\u060c \u06f4\u06f4 \u062f\u0631\u0635\u062f \u06a9\u0627\u0647\u0634 \u062a\u062e\u0641\u06cc\u0641\u0627\u062a \u0648 \u0627\u0634\u0627\u0646\u062a\u06cc\u0648\u0646 \u0631\u062e \u062f\u0627\u062f\u0647 \u06a9\u0647 \u0628\u0627 \u06a9\u0627\u0647\u0634 \u0662\u06f4 \u062f\u0631\u0635\u062f\u06cc \u0636\u0627\u06cc\u0639\u0627\u062a \u0631\u06cc\u0627\u0644\u06cc\u060c \u0645\u0646\u062c\u0631 \u0628\u0647 \u06a9\u0646\u062a\u0631\u0644 \u0628\u06cc\u0634 \u0627\u0632\u067e\u06cc\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u062f\u0631 \u0628\u0631\u0646\u062f \u0645\u0644\u06cc \u067e\u06af\u0627\u0647 \u0634\u062f.<\/p>\n<p>\u0648\u0627\u06a9\u0627\u0648\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u067e\u06af\u0627\u0647 \u062f\u0631\u0633\u0627\u0644 \u00ab\u062a\u0648\u0644\u06cc\u062f\u060c \u062f\u0627\u0646\u0634 \u0628\u0646\u06cc\u0627\u0646 \u0648 \u0627\u0634\u062a\u063a\u0627\u0644 \u0622\u0641\u0631\u06cc\u0646\u00bb \u0647\u0645 \u062e\u0628\u0631 \u0627\u0632 \u062e\u0648\u062f\u06a9\u0641\u0627\u06cc\u06cc \u0648 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062f\u0627\u0646\u0634 \u0628\u0646\u06cc\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f\u061b \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647  \u062a\u0648\u0644\u06cc\u062f \u062f\u0627\u062e\u0644\u06cc \u067e\u0648\u062f\u0631\u0627\u0633\u062a\u0627\u0628\u06cc\u0644\u0627\u06cc\u0632\u0631 \u00ab\u062c\u06cc \u0662\u0660\u00bb (\u0639\u0627\u0645\u0644 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u0627\u0631\u0632\u06cc \u0663\u0662 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646\u06cc \u0633\u0627\u0644\u0627\u0646\u0647)\u060c \u062a\u062c\u0627\u0631\u06cc \u0633\u0627\u0632\u06cc \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644 \u062f\u0627\u0646\u0634 \u0628\u0646\u06cc\u0627\u0646 \u00ab\u06a9\u0627\u063a\u0630 \u067e\u0627\u0631\u0686\u0645\u0646\u062a\u00bb \u0648 \u062a\u0648\u0644\u06cc\u062f \u00ab\u0634\u06cc\u0631\u062e\u0634\u06a9 \u0627\u0633\u06a9\u06cc\u0645 \u067e\u0627\u06cc\u0647 \u0646\u0648\u0632\u0627\u062f\u00bb \u0628\u0627\u0639\u062b \u0628\u06cc\u200c\u0646\u06cc\u0627\u0632\u06cc \u067e\u06af\u0627\u0647 \u0648 \u0635\u0646\u0639\u062a \u0644\u0628\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0648\u0632\u0647\u200c\u0647\u0627 \u0634\u062f.<\/p>\n<p>\u0627\u0632 \u0633\u0648\u06cc \u062f\u06cc\u06af\u0631\u060c \u062f\u0631\u0628\u062e\u0634 \u0635\u062f\u0648\u0631\u0645\u062d\u0635\u0648\u0644\u0627\u062a\u060c \u0635\u0627\u062f\u0631\u0627\u062a \u0662\u0660 \u062a\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u067e\u06af\u0627\u0647 \u0628\u0647 \u0645\u0644\u0628\u0648\u0631\u0646 \u0627\u0633\u062a\u0631\u0627\u0644\u06cc\u0627\u060c \u062a\u0648\u0633\u0639\u0647 \u062d\u062c\u0645 \u0635\u0627\u062f\u0631\u0627\u062a \u0628\u0647 \u0645\u0646\u0637\u0642\u0647 \u0627\u0648\u0631\u0627\u0633\u06cc\u0627 \u0648 \u0631\u06a9\u0648\u0631\u062f\u0632\u0646\u06cc \u0645\u0627\u0647\u0627\u0646\u0647 \u0635\u0627\u062f\u0631\u0627\u062a \u0661.\u06f5 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631\u06cc \u0634\u06cc\u0631\u062e\u0634\u06a9 \u0646\u0648\u0632\u0627\u062f \u200c\u0627\u0632 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0634\u0627\u062e\u0635 \u0628\u0648\u062f.<\/p>\n<p>\u062f\u0631 \u0628\u062e\u0634 \u062a\u0648\u0644\u06cc\u062f \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u0628\u0648\u0645\u06cc \u0633\u0627\u0632\u06cc \u0633\u0627\u062e\u062a \u0642\u0637\u0639\u0627\u062a \u0645\u0647\u0645 \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u062f\u0631 \u062f\u0627\u062e\u0644 \u06a9\u0634\u0648\u0631 \u0646\u06cc\u0632\u060c \u0637\u06cc \u0647\u0645\u06cc\u0646 \u0627\u06cc\u0627\u0645\u060c \u067e\u06af\u0627\u0647 \u0628\u0627 \u0633\u0627\u062e\u062a \u062f\u0627\u062e\u0644\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u00ab\u06cc\u0648 \u0627\u0686 \u062a\u06cc\u00bb \u067e\u06af\u0627\u0647 \u0641\u0627\u0631\u0633 \u0648 \u0627\u0641\u062a\u062a\u0627\u062d \u067e\u0631\u0648\u0698\u0647 \u062f\u0633\u062a\u06af\u0627\u0647 \u0628\u0633\u062a\u0647\u200c\u0628\u0646\u062f\u06cc \u067e\u06af\u0627\u0647 \u0627\u0631\u0648\u0645\u06cc\u0647 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u0626\u06cc \u0627\u0631\u0632\u06cc \u0648\u0639\u062f\u0645 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0631\u0627 \u0631\u0642\u0645 \u0632\u062f.<\/p>\n<p>\u06af\u0641\u062a\u0646\u06cc \u0627\u0633\u062a\u060c \u062a\u062d\u0642\u0642 \u0622\u0645\u0627\u0631\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631\u0648 \u062a\u0648\u0633\u0639\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0628\u0627 \u0627\u06cc\u062c\u0627\u062f \u0646\u06af\u0627\u0647\u06cc \u062a\u0627\u0632\u0647 \u062f\u0631\u0628\u0627\u0632\u0627\u0631 \u062f\u0627\u062e\u0644\u06cc \u0648 \u062e\u0627\u0631\u062c\u06cc\u060c \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0633\u0628 \u0634\u062f \u06a9\u0647 \u0633\u06cc\u0627\u0633\u062a\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062a\u0627\u0632\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u06a9\u0634\u0648\u0631 \u0648 \u062a\u062d\u0648\u0644\u0627\u062a \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0631\u06cc\u0633\u06a9 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0633\u062a \u0631\u0634\u062f \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0631\u0627 \u0628\u0627 \u0686\u0627\u0644\u0634 \u0631\u0648\u0628\u0631\u0648 \u0633\u0627\u0632\u062f.<\/p>\n<p>\u0634\u0627\u06cc\u0627\u0646 \u0630\u06a9\u0631 \u0627\u0633\u062a \u06a9\u0647 #\u0634\u0631\u06a9\u062a\u0635\u0646\u0627\u06cc\u0639\u0634\u06cc\u0631\u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0661\u0667 \u0634\u0631\u06a9\u062a \u062a\u0648\u0644\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0644\u0628\u0646\u06cc \u062f\u0631 \u0661\u06f4 \u0627\u0633\u062a\u0627\u0646 \u0639\u0627\u0645\u0644 \u0627\u0634\u062a\u063a\u0627\u0644 \u0661\u0661 \u0647\u0632\u0627\u0631 \u0646\u0641\u0631 \u0628\u0648\u062f\u0647 \u0648 \u0647\u0645 \u0627\u06a9\u0646\u0648\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0635\u0627\u062f\u0631 \u06a9\u0646\u0646\u062f\u0647 \u0645\u0645\u062a\u0627\u0632 \u0645\u0644\u06cc \u062f\u0631 \u062c\u0627\u06cc\u06af\u0627\u0647 \u06f6\u0660 (\u062f\u0631 \u062c\u0645\u0639) \u0661\u0660\u0660 \u0634\u0631\u06a9\u062a \u0628\u0631\u062a\u0631 \u0627\u06cc\u0631\u0627\u0646\u06cc \u062f\u0631 \u0633\u0627\u0644 \u0661\u06f4\u0660\u0660 \u0627\u0633\u062a.<br \/>\n\u06a9\u0633\u0628 \u0631\u062a\u0628\u0647 \u0646\u062e\u0633\u062a \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0635\u0646\u0627\u06cc\u0639 \u063a\u0630\u0627\u06cc\u06cc \u0648 \u0644\u0628\u0646\u06cc \u062f\u0631 \u06a9\u0646\u0627\u0631\u0639\u0646\u0627\u0648\u06cc\u0646\u06cc \u0686\u0648\u0646\u060c \u0633\u0631\u0622\u0645\u062f \u0635\u0646\u0627\u06cc\u0639 \u0644\u0628\u0646\u06cc \u0648 \u0627\u062e\u0630 \u06f6\u06f5 \u0646\u0634\u0627\u0646 \u0627\u06cc\u0645\u0646\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a \u0627\u0632 \u0633\u0627\u0632\u0645\u0627\u0646 \u063a\u0630\u0627 \u0648 \u062f\u0627\u0631\u0648 \u062f\u0633\u062a\u0627\u0648\u0631\u062f \u0647\u0627\u06cc \u0645\u0644\u06cc #\u067e\u06af\u0627\u0647 \u062f\u0631 \u062d\u0648\u0632\u0647 \u0633\u0644\u0627\u0645\u062a \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0631\u0631\u0633\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0631\u0627\u06cc\u0631\u0627\u0646 (\u067e\u06af\u0627\u0647) \u062f\u0631 \u0628\u0647\u0627\u0631 \u0661\u06f4\u0660\u0661 \u0627\u0632 \u0631\u0634\u062f \u062f\u0633\u062a\u0647 \u062c\u0645\u0639\u06cc \u0634\u0627\u062e\u0635\u200c\u0647\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a\u06cc \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062d\u06a9\u0627\u06cc\u062a \u062f\u0627\u0631\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0648 \u0627\u0645\u0648\u0631 \u0628\u064a\u0646 \u0627\u0644\u0645\u0644\u0644 \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0631 \u0627\u06cc\u0631\u0627\u0646 (\u067e\u06af\u0627\u0647)\u060c \u0645\u0642\u0627\u06cc\u0633\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0663 \u0645\u0627\u0647\u0647 \u0646\u062e\u0633\u062a \u0633\u0627\u0644 \u0661\u06f4\u0660\u0661 \u0628\u0647 \u0628\u0647\u0627\u0631 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u062e\u0628\u0631 \u0627\u0632 \u062a\u062d\u0642\u0642 \u0633\u0648\u062f \u0661\u06f5\u0663 \u062f\u0631\u0635\u062f\u06cc\u060c [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":81714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-81713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-158"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/81713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=81713"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/81713\/revisions"}],"predecessor-version":[{"id":81715,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/81713\/revisions\/81715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/81714"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=81713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=81713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=81713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}