{"id":76392,"date":"2022-04-09T21:55:15","date_gmt":"2022-04-09T21:55:15","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=76392"},"modified":"2022-04-09T21:55:15","modified_gmt":"2022-04-09T21:55:15","slug":"%d9%85%d8%b9%d8%a7%d9%88%d9%86%d8%aa-%d8%a8%d8%b1%d8%b1%d8%b3%db%8c%e2%80%8c%d9%87%d8%a7%db%8c-%d8%a7%d9%82%d8%aa%d8%b5%d8%a7%d8%af%db%8c-%d8%a7%d8%aa%d8%a7%d9%82-%d8%a8%d8%a7%d8%b2%d8%b1%da%af%d8%a7","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/76392","title":{"rendered":"\u0645\u0639\u0627\u0648\u0646\u062a \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u062a\u0647\u0631\u0627\u0646 \u062a\u0634\u0631\u06cc\u062d \u06a9\u0631\u062f \u0628\u0627\u0644\u0627\u062a\u0631\u06cc\u0646 \u062a\u0648\u0631\u0645 10 \u0633\u0627\u0644 \u0627\u062e\u06cc\u0631 \u0628\u0631\u0627\u06cc \u0633\u0627\u0644 1400"},"content":{"rendered":"<p>\n\u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0648 \u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0627\u0632 \u0633\u0627\u0644 1357 \u062a\u0627\u06a9\u0646\u0648\u0646 \u06cc\u0639\u0646\u06cc \u0637\u06cc 44 \u0633\u0627\u0644 \u0645\u0646\u062a\u0647\u06cc \u0628\u0647 1400\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0641\u0642\u0637 \u0637\u06cc 4 \u0633\u0627\u0644 \u062a\u0648\u0631\u0645 \u062a\u06a9\u200c\u0631\u0642\u0645\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u060c\u0645\u0639\u0627\u0648\u0646\u062a \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u062a\u0647\u0631\u0627\u0646 \u0628\u0627 \u0627\u0633\u062a\u0646\u0627\u062f \u0628\u0647 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0648 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc\u060c \u062c\u0632\u0626\u06cc\u0627\u062a \u062a\u0648\u0631\u0645 \u062f\u0631 \u0633\u0627\u0644 1400 \u0631\u0627 \u062a\u0634\u0631\u06cc\u062d \u06a9\u0631\u062f. \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0628\u0627\u0644\u0627\u062a\u0631\u06cc\u0646 \u0646\u0631\u062e \u062a\u0648\u0631\u0645\u060c \u0637\u06cc 10 \u0633\u0627\u0644 \u0627\u062e\u06cc\u0631 \u0645\u0646\u062a\u0647\u06cc \u0628\u0647 \u0633\u0627\u0644 1400 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u0633\u0627\u0644 \u0648 \u0628\u0627 \u0631\u0642\u0645 40.2 \u062f\u0631\u0635\u062f \u0628\u0648\u062f.<\/p>\n<p>\u0628\u0631 \u0627\u0633\u0627\u0633 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc\u060c \u0627\u0632 \u0633\u0627\u0644 1357 \u062a\u0627\u06a9\u0646\u0648\u0646 \u06cc\u0639\u0646\u06cc \u0637\u06cc 44 \u0633\u0627\u0644 \u0645\u0646\u062a\u0647\u06cc \u0628\u0647 1400\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0641\u0642\u0637 \u0637\u06cc 4 \u0633\u0627\u0644 \u062a\u0648\u0631\u0645 \u062a\u06a9 \u0631\u0642\u0645\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u06af\u0632\u0627\u0631\u0634 \u0645\u0639\u0627\u0648\u0646\u062a \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u062a\u0627\u0642 \u062a\u0647\u0631\u0627\u0646 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a: \u0628\u0639\u062f \u0627\u0632 \u0633\u0627\u0644 1374 \u0628\u0627 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 49.4 \u062f\u0631\u0635\u062f\u06cc\u060c \u0633\u0627\u0644 1400 \u062f\u0648\u0645\u06cc\u0646 \u0633\u0627\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627\u06cc 40 \u062f\u0631\u0635\u062f \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0633\u0627\u0644 1398 \u0631\u0627 \u0628\u0631\u0627\u0628\u0631 \u0628\u0627 41.2 \u062f\u0631\u0635\u062f \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a \u0645\u0628\u0646\u0627 \u0642\u0631\u0627\u0631\u062f\u0627\u062f\u0646 \u0646\u0631\u062e \u0645\u0632\u0628\u0648\u0631\u060c \u062a\u0648\u0627\u062a\u0631 \u062a\u062c\u0631\u0628\u0647 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627\u06cc 40 \u062f\u0631\u0635\u062f \u0637\u06cc \u062f\u0648\u0631\u0647 \u0645\u0632\u0628\u0648\u0631 \u0628\u0647 3 \u0633\u0627\u0644 \u0648 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 30 \u0627\u0644\u06cc 40 \u062f\u0631\u0635\u062f \u0628\u0647 4 \u0628\u0627\u0631 \u062a\u063a\u06cc\u06cc\u0631 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f.<\/p>\n<p>\u06a9\u0627\u0647\u0634 \u0633\u0631\u0639\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0627\u0647\u0627\u0646\u0647 \u062a\u0648\u0631\u0645<\/p>\n<p>\u062f\u0631 \u062f\u0648\u0627\u0632\u062f\u0647\u0645\u06cc\u0646 \u0645\u0627\u0647 \u0633\u0627\u0644 1400\u060c \u0646\u0631\u062e \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0645\u0627\u0647\u0627\u0646\u0647 \u0634\u0627\u062e\u0635 \u0628\u0647\u0627\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627 \u0648 \u062e\u062f\u0645\u0627\u062a \u0645\u0635\u0631\u0641\u06cc \u062e\u0627\u0646\u0648\u0627\u0631\u0647\u0627\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0647 1.3 \u062f\u0631\u0635\u062f \u0631\u0633\u06cc\u062f \u06a9\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 \u0631\u0642\u0645 \u0645\u0634\u0627\u0628\u0647 \u0645\u0627\u0647 \u0642\u0628\u0644\u060c \u0627\u0632 \u0633\u0631\u0639\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0627\u0647\u0627\u0646\u0647 \u0634\u0627\u062e\u0635 \u06a9\u0627\u0633\u062a\u0647 \u0634\u062f. \u062a\u0648\u0631\u0645 \u0646\u0642\u0637\u0647 \u0628\u0647 \u0646\u0642\u0637\u0647 \u0627\u0633\u0641\u0646\u062f 1400 (\u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u0633\u0641\u0646\u062f \u0633\u0627\u0644 \u0642\u0628\u0644) 34.7 \u062f\u0631\u0635\u062f \u0648 \u0637\u06cc 12 \u0645\u0627\u0647 \u0645\u0646\u062a\u0647\u06cc \u0628\u0647 \u0627\u0633\u0641\u0646\u062f \u0645\u0627\u0647 \u0646\u06cc\u0632 40.2 \u062f\u0631\u0635\u062f (\u0647\u0645\u0627\u0646 \u062a\u0648\u0631\u0645 \u06a9\u0644 \u0633\u0627\u0644) \u0627\u0639\u0644\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0648\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0633\u062a\u0627\u06cc\u06cc \u062f\u0631 \u0633\u0627\u0644 1400 \u0628\u0631\u0627\u0628\u0631 \u0628\u0627 42.8 \u062f\u0631\u0635\u062f \u0648 \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0648\u0627\u0631\u0647\u0627\u06cc \u0634\u0647\u0631\u06cc \u0628\u0631\u0627\u0628\u0631 \u0628\u0627 39.7 \u062f\u0631\u0635\u062f \u0628\u0648\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0637\u06cc \u0633\u0627\u0644 1400 \u0639\u0648\u0627\u0645\u0644 \u0627\u062b\u0631\u06af\u0630\u0627\u0631 \u0628\u0631 \u062a\u062d\u0642\u0642 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 40.2 \u062f\u0631\u0635\u062f\u06cc\u060c \u0645\u0634\u0627\u0631\u06a9\u062a28.8 \u0648\u0627\u062d\u062f \u062f\u0631\u0635\u062f\u06cc \u06af\u0631\u0648\u0647 \u06a9\u0627\u0644\u0627\u06cc\u06cc \u0648 11.4 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u06cc \u06af\u0631\u0648\u0647 \u062e\u062f\u0645\u0627\u062a \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u0641\u06a9\u06cc\u06a9 \u06af\u0631\u0648\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u062f\u0647\u060c \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0645\u0634\u0627\u0631\u06a9\u062a\u200c\u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u062a\u0648\u0631\u0645 \u0633\u0627\u0644 1400\u060c \u06af\u0631\u0648\u0647 \u062e\u0648\u0631\u0627\u06a9\u06cc\u200c\u0647\u0627 \u0648 \u0622\u0634\u0627\u0645\u06cc\u062f\u0646\u06cc\u200c\u0647\u0627 \u0628\u0627 \u0633\u0647\u0645 16.7 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u060c \u0645\u0633\u06a9\u0646 (\u0634\u0627\u0645\u0644 \u0627\u062c\u0627\u0631\u0647 \u0648 \u062e\u062f\u0645\u0627\u062a \u062a\u0639\u0645\u06cc\u0631 \u0645\u0633\u06a9\u0646) \u0628\u0627 \u0633\u0647\u0645 6.6 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u060c \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644 \u0628\u0627 \u0633\u0647\u0645 4.5 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u060c \u067e\u0648\u0634\u0627\u06a9 \u0648 \u06a9\u0641\u0634 \u0628\u0627 \u0633\u0647\u0645 2.7 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u060c \u0645\u0628\u0644\u0645\u0627\u0646 \u0648 \u0644\u0648\u0627\u0632\u0645 \u062e\u0627\u0646\u06af\u06cc \u0628\u0627 \u0633\u0647\u0645 2.4  \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f \u0648 \u0628\u0647\u062f\u0627\u0634\u062a \u0648 \u062f\u0631\u0645\u0627\u0646 \u0628\u0627 \u0633\u0647\u0645 2.2 \u0648\u0627\u062d\u062f \u062f\u0631\u0635\u062f \u0648 \u062f\u0631 \u0645\u062c\u0645\u0648\u0639 \u0628\u0627 \u0633\u0647\u0645 30.7 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u06cc \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u062e\u0635 \u0628\u0647\u0627\u06cc \u06af\u0631\u0648\u0647 \u0627\u0646\u0631\u0698\u06cc (\u0622\u0628\u060c \u0628\u0631\u0642 \u0648 \u0633\u0648\u062e\u062a) \u062f\u0631 \u0633\u0627\u0644 1400 \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u0644 \u0642\u0628\u0644\u060c \u062d\u062f\u0648\u062f 24.5 \u062f\u0631\u0635\u062f \u0648 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0634\u0627\u0631\u06a9\u062a \u0622\u0646 \u062f\u0631 \u062a\u0648\u0631\u0645 \u0633\u0627\u0644 \u0645\u0632\u0628\u0648\u0631 \u0631\u0642\u0645\u06cc \u06a9\u0645 \u0648 \u062d\u062f\u0648\u062f 0.7 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f \u0627\u0633\u062a. \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u062e\u0635 \u0628\u0647\u0627\u06cc \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u0633\u0627\u0644 1400 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u06af\u0631\u0648\u0647 \u062e\u062f\u0645\u0627\u062a\u06cc \u0627\u0631\u062a\u0628\u0627\u0637\u0627\u062a\u060c \u0628\u0627 \u0646\u0631\u062e 6.4 \u062f\u0631\u0635\u062f \u0648 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0645\u0634\u0627\u0631\u06a9\u062a \u0646\u06cc\u0632 \u0645\u062a\u0639\u0644\u0642 \u0628\u0647 \u0627\u06cc\u0646 \u06af\u0631\u0648\u0647 \u0628\u0627 \u0633\u0647\u06450.12 \u0648\u0627\u062d\u062f \u062f\u0631\u0635\u062f\u06cc \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0645\u06cc\u0627\u0646 \u0627\u0642\u0644\u0627\u0645 \u062e\u0648\u0631\u0627\u06a9\u06cc \u0648 \u0622\u0634\u0627\u0645\u06cc\u062f\u0646\u06cc \u0633\u0647 \u06af\u0631\u0648\u0647 \u06a9\u0627\u0644\u0627\u06cc\u06cc \u0634\u0627\u0645\u0644\u060c \u0646\u0627\u0646 \u0648 \u063a\u0644\u0627\u062a\u060c \u06af\u0648\u0634\u062a \u0642\u0631\u0645\u0632 \u0648 \u0645\u0627\u06a9\u06cc\u0627\u0646 \u0648 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u062f\u0631 \u0645\u062c\u0645\u0648\u0639 \u062d\u062f\u0648\u062f 50 \u062f\u0631\u0635\u062f \u0627\u0632 \u0645\u0634\u0627\u0631\u06a9\u062a 16.74 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f\u06cc \u06af\u0631\u0648\u0647 \u062e\u0648\u0631\u0627\u06a9\u06cc \u0647\u0627 \u0648 \u0622\u0634\u0627\u0645\u06cc\u062f\u0646\u06cc \u0647\u0627 \u0631\u0627 \u062f\u0631 \u062a\u0648\u0631\u0645 1400 \u062a\u0634\u06a9\u06cc\u0644 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n<p>\u0627\u0632 \u0645\u0646\u0638\u0631 \u0637\u0628\u0642\u0647\u200c\u0628\u0646\u062f\u06cc \u06a9\u0627\u0644\u0627\u06cc\u06cc \u0628\u0631 \u062d\u0633\u0628 \u0645\u0627\u0646\u062f\u06af\u0627\u0631\u06cc\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0645\u0634\u0627\u0631\u06a9\u062a \u062f\u0631 \u062a\u0648\u0631\u0645 \u0633\u0627\u0644 1400 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u06af\u0631\u0648\u0647 \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0628\u06cc\u200c\u062f\u0648\u0627\u0645 \u0628\u0627 21.4 \u0648\u0627\u062d\u062f\u062f\u0631\u0635\u062f \u0633\u0647\u0645 \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0648 \u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0627\u0632 \u0633\u0627\u0644 1357 \u062a\u0627\u06a9\u0646\u0648\u0646 \u06cc\u0639\u0646\u06cc \u0637\u06cc 44 \u0633\u0627\u0644 \u0645\u0646\u062a\u0647\u06cc \u0628\u0647 1400\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0641\u0642\u0637 \u0637\u06cc 4 \u0633\u0627\u0644 \u062a\u0648\u0631\u0645 \u062a\u06a9\u200c\u0631\u0642\u0645\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u060c\u0645\u0639\u0627\u0648\u0646\u062a \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u062a\u0647\u0631\u0627\u0646 \u0628\u0627 \u0627\u0633\u062a\u0646\u0627\u062f \u0628\u0647 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0648 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc\u060c [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":76393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[158],"tags":[],"class_list":["post-76392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-158"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/76392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=76392"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/76392\/revisions"}],"predecessor-version":[{"id":76394,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/76392\/revisions\/76394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/76393"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=76392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=76392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=76392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}