{"id":72749,"date":"2022-02-25T09:00:13","date_gmt":"2022-02-25T10:00:13","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=72749"},"modified":"2022-02-25T09:00:13","modified_gmt":"2022-02-25T10:00:13","slug":"%d8%aa%d9%88%d8%b3%d8%b7-%d9%85%d8%b9%d8%a7%d9%88%d9%86%d8%aa-%d8%a7%d9%85%d9%88%d8%b1-%d8%a8%d8%a7%d9%86%da%a9%db%8c%d8%8c-%d8%a8%db%8c%d9%85%d9%87-%d9%88-%d8%b4%d8%b1%da%a9%d8%aa%e2%80%8c%d9%87","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/72749","title":{"rendered":"\u062a\u0648\u0633\u0637 \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0645\u0648\u0631 \u0628\u0627\u0646\u06a9\u06cc\u060c \u0628\u06cc\u0645\u0647 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc \u0627\u0639\u0644\u0627\u0645 \u0634\u062f \u0628\u0627\u0646\u06a9 \u0631\u0641\u0627\u0647 \u06a9\u0627\u0631\u06af\u0631\u0627\u0646 \u062d\u0627\u0626\u0632 \u0631\u062a\u0628\u0647 \u062f\u0648\u0645 \u06a9\u0634\u0648\u0631\u06cc \u062f\u0631 \u067e\u0631\u062f\u0627\u062e\u062a \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646"},"content":{"rendered":"<p>\n \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0639\u0644\u0627\u0645 \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0645\u0648\u0631 \u0628\u0627\u0646\u06a9\u06cc\u060c \u0628\u06cc\u0645\u0647 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u060c \u0628\u0627\u0646\u06a9 \u0631\u0641\u0627\u0647 \u06a9\u0627\u0631\u06af\u0631\u0627\u0646 \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06f2\u06f5 \u0647\u0632\u0627\u0631 \u0648 \u06f3\u06f3\u06f2 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062f\u0631 \u0628\u0647\u0645\u0646 \u0645\u0627\u0647 \u0633\u0627\u0644 \u062c\u0627\u0631\u06cc\u060c \u062d\u0627\u0626\u0632 \u0631\u062a\u0628\u0647 \u062f\u0648\u0645 \u06a9\u0634\u0648\u0631\u06cc \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u067e\u0631\u062f\u0627\u062e\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0628\u0647 \u0645\u062a\u0642\u0627\u0636\u06cc\u0627\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u0646\u06cc\u0645\u0647\u200c\u062f\u0648\u0644\u062a\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u0627\u0646\u06a9 \u0631\u0641\u0627\u0647 \u06a9\u0627\u0631\u06af\u0631\u0627\u0646  \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0645\u0648\u0631 \u0628\u0627\u0646\u06a9\u06cc\u060c \u0628\u06cc\u0645\u0647 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0628\u06cc\u0634 \u0627\u0632 \u06f2\u06f6 \u0647\u0632\u0627\u0631 \u0648 \u06f8\u06f9\u06f1 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062e\u0631\u062f \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646\u060c \u062a\u0648\u0633\u0637 \u06f1\u06f1 \u0628\u0627\u0646\u06a9 \u062f\u0648\u0644\u062a\u06cc \u0648 \u0646\u06cc\u0645\u0647 \u062f\u0648\u0644\u062a\u06cc \u062f\u0631 \u0628\u0647\u0645\u0646 \u0645\u0627\u0647 \u0633\u0627\u0644\u200c\u062c\u0627\u0631\u06cc \u062e\u0628\u0631 \u062f\u0627\u062f.<br \/>\n\u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634\u060c \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0645\u0648\u0631 \u0628\u0627\u0646\u06a9\u06cc\u060c \u0628\u06cc\u0645\u0647 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0646\u062a\u0634\u0627\u0631 \u06af\u0632\u0627\u0631\u0634\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u06f9\u06f5 \u0647\u0632\u0627\u0631 \u0648 \u06f9\u06f8\u06f3 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062e\u0631\u062f \u062a\u0627 \u0633\u0642\u0641 \u06cc\u06a9 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u0631\u06cc\u0627\u0644 \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u062f\u0631 \u0628\u0647\u0645\u0646 \u0645\u0627\u0647 \u0627\u0645\u0633\u0627\u0644 \u062e\u0628\u0631 \u062f\u0627\u062f.<br \/>\n\u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0645\u06cc\u200c\u0627\u0641\u0632\u0627\u06cc\u062f\u060c \u0628\u0627\u0646\u06a9\u200c \u0633\u067e\u0647 \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06f4\u06f0 \u0647\u0632\u0627\u0631 \u0648 \u06f8\u06f5\u06f2 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062e\u0631\u062f\u060c \u0628\u0627\u0646\u06a9 \u0631\u0641\u0627\u0647 \u06a9\u0627\u0631\u06af\u0631\u0627\u0646 \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06f2\u06f5 \u0647\u0632\u0627\u0631 \u0648 \u06f3\u06f3\u06f2 \u0641\u0642\u0631\u0647 \u0648 \u0628\u0627\u0646\u06a9\u200c \u0642\u0631\u0635\u200c\u0627\u0644\u062d\u0633\u0646\u0647 \u0645\u0647\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0646\u06cc\u0632 \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06f1\u06f2 \u0647\u0632\u0627\u0631 \u0648 \u06f1\u06f2\u06f3 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a\u060c \u062d\u0627\u0626\u0632 \u0631\u062a\u0628\u0647 \u0627\u0648\u0644 \u062a\u0627 \u0633\u0648\u0645 \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u067e\u0631\u062f\u0627\u062e\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0628\u0647 \u0645\u062a\u0642\u0627\u0636\u06cc\u0627\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u0646\u06cc\u0645\u0647\u200c\u062f\u0648\u0644\u062a\u06cc  \u0634\u062f\u0647\u200c\u0627\u0646\u062f.<\/p>\n<p>\u0634\u0627\u062f\u0627<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0639\u0644\u0627\u0645 \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0645\u0648\u0631 \u0628\u0627\u0646\u06a9\u06cc\u060c \u0628\u06cc\u0645\u0647 \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648\u0632\u0627\u0631\u062a \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u060c \u0628\u0627\u0646\u06a9 \u0631\u0641\u0627\u0647 \u06a9\u0627\u0631\u06af\u0631\u0627\u0646 \u0628\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u06f2\u06f5 \u0647\u0632\u0627\u0631 \u0648 \u06f3\u06f3\u06f2 \u0641\u0642\u0631\u0647 \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u062f\u0631 \u0628\u0647\u0645\u0646 \u0645\u0627\u0647 \u0633\u0627\u0644 \u062c\u0627\u0631\u06cc\u060c \u062d\u0627\u0626\u0632 \u0631\u062a\u0628\u0647 \u062f\u0648\u0645 \u06a9\u0634\u0648\u0631\u06cc \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u062a\u0633\u0647\u06cc\u0644\u0627\u062a \u067e\u0631\u062f\u0627\u062e\u062a\u06cc \u0628\u062f\u0648\u0646 \u0636\u0627\u0645\u0646 \u0628\u0647 \u0645\u062a\u0642\u0627\u0636\u06cc\u0627\u0646 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u0646\u06cc\u0645\u0647\u200c\u062f\u0648\u0644\u062a\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":72750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-72749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/72749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=72749"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/72749\/revisions"}],"predecessor-version":[{"id":72751,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/72749\/revisions\/72751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/72750"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=72749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=72749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=72749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}