{"id":62093,"date":"2021-12-06T20:09:30","date_gmt":"2021-12-06T21:09:30","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=62093"},"modified":"2021-12-06T20:09:30","modified_gmt":"2021-12-06T21:09:30","slug":"%da%a9%d8%b3%d8%a8%e2%80%8c%d9%88%da%a9%d8%a7%d8%b1%d9%87%d8%a7%db%8c-%d8%ae%d9%8f%d8%b1%d8%af-%d8%af%d8%b1-%da%a9%d9%85%d8%aa%d8%b1%db%8c%d9%86-%d8%b2%d9%85%d8%a7%d9%86-%d8%a7%d9%85%da%a9%d8%a7%d9%86","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/62093","title":{"rendered":"\u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u064f\u0631\u062f \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0627\u0645\u06a9\u0627\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0646\u0645\u0627\u062f \u0628\u06cc\u200c\u0633\u062a\u0627\u0631\u0647 \u062f\u0627\u0631\u0646\u062f"},"content":{"rendered":"\n<p>\u0645\u0639\u0627\u0648\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u06af\u0641\u062a: \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0631\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644\u0627 \u0633\u06cc\u0633\u062a\u0645\u06cc \u0648 \u0628\u0631\u062e\u0637 \u0648 \u062a\u0646\u0647\u0627 \u0628\u0627 \u0627\u0631\u0627\u06cc\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0647\u0648\u06cc\u062a\u06cc \u0648 \u062f\u0627\u0645\u0646\u0647 \u062e\u0648\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u0628\u06cc\u200c\u0633\u062a\u0627\u0631\u0647 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc  \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc\u060c \u0645\u0647\u0631\u0627\u0646 \u0645\u062d\u0631\u0645\u06cc\u0627\u0646 \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u0627\u062e\u0630 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u06cc\u0646\u0645\u0627\u062f \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0648 \u0628\u0627 \u062d\u062f\u0627\u0642\u0644 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0627\u0645\u06a9\u0627\u0646\u200c\u067e\u0630\u06cc\u0631 \u0627\u0633\u062a.<\/p>\n<p>\u0648\u06cc \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0627\u0644\u0632\u0627\u0645 \u0642\u0627\u0646\u0648\u0646\u06cc \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f: \u0645\u0648\u0636\u0648\u0639 \u0627\u0644\u0632\u0627\u0645 \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u0628\u0631\u0627\u06cc \u067e\u0630\u06cc\u0631\u0646\u062f\u06af\u0627\u0646 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u062e\u062a\u200c\u06cc\u0627\u0631 \u0628\u0647 \u0627\u0633\u062a\u0646\u0627\u062f \u0645\u0627\u062f\u0647 \u0661\u0660\u0663 \u0622\u06cc\u06cc\u0646 \u0646\u0627\u0645\u0647 \u0627\u062c\u0631\u0627\u06cc\u06cc \u0645\u0627\u062f\u0647 \u0661\u06f4 \u0627\u0644\u062d\u0627\u0642\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u067e\u0648\u0644\u0634\u0648\u06cc\u06cc \u0627\u062c\u0631\u0627\u06cc\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0622\u06cc\u06cc\u0646 \u0646\u0627\u0645\u0647 \u0645\u0635\u0648\u0628 \u0622\u0628\u0627\u0646 \u0645\u0627\u0647 \u0633\u0627\u0644 \u06f1\u06f3\u06f9\u06f8 \u0647\u06cc\u0627\u062a \u062f\u0648\u0644\u062a \u0628\u0648\u062f\u0647 \u0648 \u0637\u06cc \u0628\u06cc\u0634 \u0627\u0632 \u062f\u0648 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u062a\u0644\u0627\u0634 \u0634\u062f\u0647 \u0628\u0647 \u0637\u0648\u0631 \u062a\u062f\u0631\u06cc\u062c\u06cc \u0627\u062c\u0631\u0627\u06cc \u062a\u06a9\u0627\u0644\u06cc\u0641 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0627\u062e\u062a\u0644\u0627\u0644\u06cc \u062f\u0631 \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627 \u0627\u06cc\u062c\u0627\u062f \u0646\u0634\u0648\u062f\u060c \u067e\u06cc\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u0645\u0639\u0627\u0648\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc \u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0627\u0641\u0632\u0648\u062f: \u0627\u0644\u0632\u0627\u0645 \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u0628\u0631\u0627\u06cc \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0647\u0627\u06cc \u0645\u062c\u0627\u0632\u06cc \u06a9\u0647 \u062f\u0631\u06af\u0627\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc psp \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0631\u062f\u0647 \u0627\u0646\u062f \u0627\u0632 \u0632\u0645\u0633\u062a\u0627\u0646 \u0633\u0627\u0644 \u06f9\u06f8  \u0627\u062c\u0631\u0627\u06cc\u06cc \u0634\u062f\u0647 \u0648 \u067e\u0630\u06cc\u0631\u0646\u062f\u06af\u0627\u0646 \u062c\u062f\u06cc\u062f \u0641\u0639\u0627\u0644 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0645\u062c\u0627\u0632\u06cc \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u062e\u0630 \u0634\u0645\u0627\u0631\u0647 \u067e\u06cc\u06af\u06cc\u0631\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u0644\u0632\u0645 \u0628\u0647 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0646\u0645\u0627\u062f \u0627\u0632 \u0645\u0631\u06a9\u0632 \u062a\u0648\u0633\u0639\u0647 \u062a\u062c\u0627\u0631\u062a \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0628\u0648\u062f\u0647 \u0627\u0646\u062f.<\/p>\n<p>\u0645\u062d\u0631\u0645\u06cc\u0627\u0646 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0631\u062f\u060c \u0645\u0631\u06a9\u0632 \u062a\u0648\u0633\u0639\u0647 \u062a\u062c\u0627\u0631\u062a \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0637\u0631\u0627\u062d\u06cc \u0646\u0645\u0627\u062f \u0628\u06cc \u0633\u062a\u0627\u0631\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u0627\u062e\u0630 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u06cc\u0646\u0645\u0627\u062f \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0648 \u0628\u0627 \u062d\u062f\u0627\u0642\u0644 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0627\u0645\u06a9\u0627\u0646 \u067e\u0630\u06cc\u0631 \u0627\u0633\u062a. \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0631\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644\u0627 \u0633\u06cc\u0633\u062a\u0645\u06cc \u0648 \u0628\u0631\u062e\u0637 \u0648 \u0635\u0631\u0641\u0627 \u0628\u0627 \u0627\u0631\u0627\u06cc\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0647\u0648\u06cc\u062a\u06cc \u0648 \u062f\u0627\u0645\u0646\u0647 \u062e\u0648\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u062e\u0630 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u06cc\u0646\u0645\u0627\u062f \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0648\u06cc \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0627\u0647\u0644\u06cc\u062a \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627 \u062f\u0631 \u0641\u0636\u0627\u06cc \u0645\u062c\u0627\u0632\u06cc \u0627\u0633\u062a\u060c \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0646\u0634\u0627\u0646 \u062f\u0631 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u067e\u0630\u06cc\u0631\u0646\u062f\u06af\u0627\u0646 \u0641\u0636\u0627\u06cc \u0645\u062c\u0627\u0632\u06cc \u0645\u0648\u062c\u0628\u0627\u062a \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u06cc\u0634\u062a\u0631 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u06a9\u0646\u062f.<\/p>\n<p>\u0645\u0639\u0627\u0648\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc \u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u062f\u0631 \u067e\u0627\u06cc\u0627\u0646 \u062e\u0627\u0637\u0631 \u0646\u0634\u0627\u0646 \u06a9\u0631\u062f: \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0647\u0645\u0648\u0627\u0631\u0647 \u0627\u0647\u062a\u0645\u0627\u0645 \u0648\u06cc\u0698\u0647 \u0627\u06cc \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc  \u0642\u0648\u0627\u0646\u06cc\u0646 \u0645\u062c\u0644\u0633 \u0648 \u0645\u0635\u0648\u0628\u0627\u062a \u0647\u06cc\u0627\u062a \u062f\u0648\u0644\u062a \u062f\u0627\u0631\u062f\u061b \u062f\u0631 \u0627\u06cc\u0646 \u062e\u0635\u0648\u0635 \u0646\u06cc\u0632 \u067e\u06cc\u0634 \u0627\u0632 \u0627\u062c\u0631\u0627 \u062a\u0644\u0627\u0634 \u06a9\u0631\u062f\u0647 \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0628\u0627 \u0645\u0631\u06a9\u0632 \u062a\u0648\u0633\u0639\u0647 \u062a\u062c\u0627\u0631\u062a \u0645\u0648\u062c\u0628 \u06a9\u0627\u0647\u0634 \u062f\u063a\u062f\u063a\u0647\u200c\u0647\u0627\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627 \u0634\u0648\u062f \u0648 \u0647\u0631 \u06af\u0648\u0646\u0647 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u0633\u0647\u06cc\u0644 \u0634\u0631\u0648\u0639 \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627 \u0634\u0648\u062f \u0631\u0627 \u0645\u0648\u0631\u062f \u0628\u0631\u0631\u0633\u06cc \u0642\u0631\u0627\u0631 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u06cc\u0631\u0646\u0627\u060c \u0647\u0645\u0647 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0632 \u0633\u0648\u0645 \u0622\u0630\u0631\u0645\u0627\u0647 \u0645\u0644\u0632\u0645 \u0634\u062f\u0647 \u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u062f\u0631\u06af\u0627\u0647 \u067e\u0631\u062f\u0627\u062e\u062a\u060c \u0627\u06cc\u0646\u0645\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0644\u0632\u0627\u0645 \u062f\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0646\u0645\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0648 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0641\u0627\u0641\u06cc\u062a \u0645\u0627\u0644\u06cc \u0648 \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u067e\u0648\u0644\u0634\u0648\u06cc\u06cc \u0645\u06cc \u0634\u0648\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u062e\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627 \u0646\u0633\u0628\u062a \u0628\u0647 \u0622\u0646 \u06af\u0644\u0627\u06cc\u0647 \u062f\u0627\u0634\u062a\u0647 \u0648 \u0645\u0639\u062a\u0642\u062f \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0634\u06cc\u0648\u0647 \u06a9\u0646\u0648\u0646\u06cc \u0627\u0644\u0632\u0627\u0645 \u062f\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u06cc\u0646\u0645\u0627\u062f\u060c \u0633\u0631\u0639\u062a \u0631\u0634\u062f \u0627\u0633\u062a\u0627\u0631\u062a\u0627\u067e\u200c\u0647\u0627 \u0648 \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0631\u062f \u0631\u0627 \u062e\u0648\u0627\u0647\u062f \u06af\u0631\u0641\u062a \u0648 \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0633\u0628 \u0648\u06a9\u0627\u0631\u0647\u0627 \u0644\u0637\u0645\u0647 \u062e\u0648\u0627\u0647\u062f \u0632\u062f.<\/p>\n<p>\u0627\u06cc\u0646\u0645\u0627\u062f (E-Namad) \u06cc\u0627 \u0646\u0645\u0627\u062f \u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc\u060c \u06cc\u06a9 \u0646\u0645\u0627\u062f \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0637\u0631\u0641 \u0645\u0631\u06a9\u0632 \u062a\u0648\u0633\u0639\u0647 \u062a\u062c\u0627\u0631\u062a \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u0628\u0647 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u06cc\u200c\u0647\u0627 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u0636\u0648\u0627\u0628\u0637 \u0645\u0634\u062e\u0635 \u0648 \u0627\u0632 \u067e\u06cc\u0634 \u062a\u0639\u06cc\u06cc\u0646 \u0634\u062f\u0647\u200c\u0627\u06cc \u0628\u0627\u0634\u0646\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0639\u0627\u0648\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u0646\u0648\u06cc\u0646 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u06af\u0641\u062a: \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0631\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644\u0627 \u0633\u06cc\u0633\u062a\u0645\u06cc \u0648 \u0628\u0631\u062e\u0637 \u0648 \u062a\u0646\u0647\u0627 \u0628\u0627 \u0627\u0631\u0627\u06cc\u0647 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0647\u0648\u06cc\u062a\u06cc \u0648 \u062f\u0627\u0645\u0646\u0647 \u062e\u0648\u062f \u0646\u0633\u0628\u062a \u0628\u0647 \u0627\u062e\u0630 \u0627\u06cc\u0646\u0645\u0627\u062f \u0628\u06cc\u200c\u0633\u062a\u0627\u0631\u0647 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u0646\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc\u060c \u0645\u0647\u0631\u0627\u0646 \u0645\u062d\u0631\u0645\u06cc\u0627\u0646 \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u0627\u062e\u0630 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0627\u06cc\u0646\u0645\u0627\u062f \u062f\u0631 \u06a9\u0645\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0648 \u0628\u0627 \u062d\u062f\u0627\u0642\u0644 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":62094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-62093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/62093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=62093"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/62093\/revisions"}],"predecessor-version":[{"id":62095,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/62093\/revisions\/62095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/62094"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=62093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=62093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=62093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}