{"id":55308,"date":"2021-09-18T20:46:24","date_gmt":"2021-09-18T20:46:24","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=55308"},"modified":"2021-09-18T20:46:24","modified_gmt":"2021-09-18T20:46:24","slug":"%d9%85%d8%af%db%8c%d8%b1%d8%b9%d8%a7%d9%85%d9%84-%d8%b3%d8%a8%d8%af%da%af%d8%b1%d8%af%d8%a7%d9%86-%d8%a2%d8%a8%d8%a7%d9%86-%d8%a7%d8%b9%d9%84%d8%a7%d9%85-%da%a9%d8%b1%d8%af-%d8%a7%d8%a8%d8%b2%d8%a7","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/55308","title":{"rendered":"\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0633\u0628\u062f\u06af\u0631\u062f\u0627\u0646 \u0622\u0628\u0627\u0646 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f: \u0627\u0628\u0632\u0627\u0631 \u062a\u0634\u0648\u06cc\u0642\u06cc \u0633\u0627\u0632\u0645\u0627\u0646 \u0628\u0648\u0631\u0633 \u0628\u0631\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u063a\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645"},"content":{"rendered":"<p> \u0633\u0627\u0632\u0645\u0627\u0646 \u0628\u0648\u0631\u0633 \u062a\u0644\u0627\u0634 \u062f\u0627\u0631\u062f \u062a\u0627 \u0645\u0634\u0648\u0642\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0631\u0648\u06cc\u062c \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627 \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647 \u0627\u062c\u0631\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0646 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0633\u0627\u0633\u0627\u0646 \u0627\u0644\u0644\u0647 \u0642\u0644\u06cc\u060c \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0633\u0628\u062f\u06af\u0631\u062f\u0627\u0646 \u0622\u0628\u0627\u0646 \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0645\u0637\u0644\u0628 \u0641\u0648\u0642 \u062f\u0631 \u06af\u0641\u062a \u0648 \u06af\u0648 \u0628\u0627 \u067e\u0627\u06cc\u06af\u0627\u0647 \u062e\u0628\u0631\u06cc \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u06cc\u0631\u0627\u0646 (\u0633\u0646\u0627) \u0628\u0647 \u062c\u0632\u06cc\u06cc\u0627\u062a \u062f\u0642\u06cc\u0642 \u0631\u0648\u0634 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0635\u0648\u0631\u062a \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f \u0648 \u0627\u0641\u0632\u0648\u062f: \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062a\u0634\u0648\u06cc\u0642 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u0627\u0646 \u062c\u0647\u062a \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645\u060c \u0633\u0647\u0645\u06cc\u0647 \u0627\u06cc \u0627\u0636\u0627\u0641\u0647 \u0628\u0647 \u0635\u0646\u062f\u0648\u0642 \u0647\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u062a\u0639\u0644\u0642 \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0648\u06cc \u062e\u0627\u0637\u0631\u0646\u0634\u0627\u0646 \u06a9\u0631\u062f: \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u06a9\u0647 \u0628\u0631\u062e\u06cc \u06af\u0645\u0627\u0646 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u062d\u062a\u0645 \u0633\u0648\u062f\u0622\u0648\u0631 \u0628\u0627\u0634\u062f \u0648 \u0628\u0627 \u0646\u0631\u062e\u06cc \u0639\u0631\u0636\u0647 \u0634\u0648\u0646\u062f \u06a9\u0647 \u0645\u0631\u062f\u0645 \u062f\u0631 \u062f\u0631\u0648\u0646 \u0635\u0641 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u0646\u062f\u060c \u0631\u0648\u0634 \u0686\u0646\u062f\u0627\u0646 \u0645\u0646\u0627\u0633\u0628\u06cc \u0646\u06cc\u0633\u062a \u0632\u06cc\u0631\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u062f\u062a\u06cc \u0637\u0648\u0644 \u0628\u06a9\u0634\u062f \u062a\u0627 \u0633\u0647\u0627\u0645 \u0628\u0647 \u062d\u0627\u0644\u062a \u0634\u0646\u0627\u0648\u0631 \u0628\u0631\u0633\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0633\u0647\u0645\u06cc \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631 \u0634\u0648\u062f \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u0633\u0627\u0633 \u0645\u06a9\u0627\u0646\u06cc\u0632\u0645\u06cc \u0645\u0639\u0642\u0648\u0644 \u06a9\u0634\u0641 \u0646\u0631\u062e \u0634\u0648\u062f \u0648 \u0633\u0647\u0627\u0645 \u0645\u062f\u0646\u0638\u0631 \u0647\u0645 \u0631\u0648\u0632 \u0628\u0639\u062f \u0627\u0632 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0635\u0648\u0631\u062a \u0639\u0627\u062f\u06cc \u0645\u0648\u0631\u062f \u0645\u0639\u0627\u0645\u0644\u0647 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f.<\/p>\n<p>\u0627\u0644\u0644\u0647 \u0642\u0644\u06cc \u0628\u0627 \u062a\u0627\u06a9\u06cc\u062f \u0628\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0627\u0631\u0647\u0627 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u0627\u0646 \u0631\u0627 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u06a9\u0627\u0647\u0634 \u0636\u0631\u0631 \u0648 \u0632\u06cc\u0627\u0646 \u0647\u0627\u06cc \u0627\u062d\u062a\u0645\u0627\u0644\u06cc \u062a\u0634\u0648\u06cc\u0642 \u0628\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645\u060c \u062e\u0627\u0637\u0631\u0646\u0634\u0627\u0646 \u06a9\u0631\u062f: \u0633\u0627\u0632\u0645\u0627\u0646 \u0628\u0648\u0631\u0633 \u062a\u0644\u0627\u0634 \u062f\u0627\u0631\u062f \u062a\u0627 \u0645\u0634\u0648\u0642\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0631\u0648\u06cc\u062c \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627 \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647 \u0627\u062c\u0631\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0646 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0648\u06cc \u0628\u0647 \u0634\u0628\u0647\u0627\u062a \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u062f\u0631\u062e\u0635\u0648\u0635 \u0648\u062c\u0648\u062f \u062a\u0628\u0639\u06cc\u0636 \u0628\u0631\u0627\u06cc \u062a\u062e\u0635\u06cc\u0635 \u0633\u0647\u0627\u0645 \u0628\u06cc\u0646 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f \u0648 \u06af\u0641\u062a: \u0645\u06cc\u0632\u0627\u0646 \u0633\u0647\u0627\u0645 \u062f\u0631 \u0639\u0631\u0636\u0647 \u0647\u0627\u06cc \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0642\u062f\u06cc\u0645 \u0628\u0647 \u062d\u062f\u06cc \u06a9\u0648\u0686\u06a9 \u0628\u0648\u062f \u06a9\u0647 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0634\u0641\u0627\u0641 \u0635\u0648\u0631\u062a \u0646\u0645\u06cc \u06af\u0631\u0641\u062a\u060c \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0686\u0646\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0628\u0647\u062a\u0631 \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u06af\u0630\u0634\u062a\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0627\u0644\u0644\u0647 \u0642\u0644\u06cc \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f : \u0627\u06a9\u0646\u0648\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0633\u0627\u06cc\u0644 \u0642\u0627\u0628\u0644 \u0627\u0647\u0645\u06cc\u062a \u062f\u0631 \u0631\u0648\u0634 \u062c\u062f\u06cc\u062f \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647\u060c \u0645\u06cc\u0632\u0627\u0646 \u0633\u0647\u0627\u0645 \u0627\u062e\u062a\u0635\u0627\u0635 \u06cc\u0627\u0641\u062a\u0647 \u0628\u0647 \u0647\u0631 \u0635\u0646\u062f\u0648\u0642 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0637\u0631\u06cc\u0642 \u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0631\u06a9\u062a \u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062f\u0631 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0633\u0628\u062f\u06af\u0631\u062f\u0627\u0646 \u0622\u0628\u0627\u0646 \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0627\u06cc\u0646\u06a9\u0647 \u06af\u0641\u062a\u0647 \u0645\u06cc \u0634\u0648\u062f \u062f\u0631 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u062c\u062f\u06cc\u062f \u0632\u0645\u06cc\u0646\u0647 \u0627\u06cc\u062c\u0627\u062f \u0631\u0627\u0646\u062a \u0628\u0631\u0627\u06cc \u0628\u0631\u062e\u06cc \u0627\u0632 \u06af\u0631\u0648\u0647 \u0647\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc \u0634\u0648\u062f\u060c \u0635\u062d\u062a \u0646\u062f\u0627\u0631\u062f \u0627\u0645\u0627 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u062c\u062f\u06cc\u062f \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647\u060c \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u062f\u0631 \u06a9\u0634\u0641 \u0642\u06cc\u0645\u062a \u0635\u0648\u0631\u062a \u0628\u06af\u06cc\u0631\u062f.<\/p>\n<p>*\u062e\u0628\u0631\u0646\u06af\u0627\u0631: \u062f\u0646\u06cc\u0627 \u0632\u0646\u0648\u0632\u06cc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0633\u0627\u0632\u0645\u0627\u0646 \u0628\u0648\u0631\u0633 \u062a\u0644\u0627\u0634 \u062f\u0627\u0631\u062f \u062a\u0627 \u0645\u0634\u0648\u0642\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0631\u0648\u06cc\u062c \u0633\u0631\u0645\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631\u06cc \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0627\u0633\u062a\u0627 \u062a\u0635\u0645\u06cc\u0645 \u0628\u0647 \u0627\u062c\u0631\u0627\u06cc\u06cc \u06a9\u0631\u062f\u0646 \u0639\u0631\u0636\u0647 \u0627\u0648\u0644\u06cc\u0647 \u0628\u0647 \u0631\u0648\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0633\u0627\u0633\u0627\u0646 \u0627\u0644\u0644\u0647 \u0642\u0644\u06cc\u060c \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0633\u0628\u062f\u06af\u0631\u062f\u0627\u0646 \u0622\u0628\u0627\u0646 \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0645\u0637\u0644\u0628 \u0641\u0648\u0642 \u062f\u0631 \u06af\u0641\u062a \u0648 \u06af\u0648 \u0628\u0627 \u067e\u0627\u06cc\u06af\u0627\u0647 \u062e\u0628\u0631\u06cc \u0628\u0627\u0632\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u06cc\u0631\u0627\u0646 (\u0633\u0646\u0627) [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":55309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-55308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/55308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=55308"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/55308\/revisions"}],"predecessor-version":[{"id":55310,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/55308\/revisions\/55310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/55309"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=55308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=55308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=55308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}