{"id":53794,"date":"2021-08-29T19:59:43","date_gmt":"2021-08-29T19:59:43","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=53794"},"modified":"2021-08-29T19:59:43","modified_gmt":"2021-08-29T19:59:43","slug":"%d9%86%da%af%d8%a7%d9%87%db%8c-%d8%a8%d9%87-%d8%a2%db%8c%d9%86%d8%af%d9%87-%d8%b3%d8%a8%da%a9-%d8%b2%d9%86%d8%af%da%af%db%8c-%d9%87%d9%88%d8%b4%d9%85%d9%86%d8%af","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/53794","title":{"rendered":"\u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0647\u0648\u0634\u0645\u0646\u062f"},"content":{"rendered":"<p>\u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc :\u0627\u06a9\u0646\u0648\u0646 \u0628\u0647\u200c\u062c\u0627\u06cc\u06cc \u0631\u0633\u06cc\u062f\u0647\u200c\u0627\u06cc\u0645 \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u062e\u0628\u0631\u06cc \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u06cc\u200c\u0647\u0627 \u0648 \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631 \u0639\u0645\u06cc\u0642 \u062f\u0631 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0627\u0646\u0633\u0627\u0646 \u0628\u0627\u0634\u0646\u062f \u0646\u06cc\u0633\u062a. \u0627\u06af\u0631\u0686\u0647 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u062c\u062f\u06cc \u062a\u0648\u0633\u0637 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0635\u0644\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f\u060c \u0627\u0645\u0627 \u0647\u0646\u0648\u0632 \u0645\u0634\u062e\u0635 \u0646\u06cc\u0633\u062a \u06a9\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0631\u0648\u0627\u0642\u0639 \u0628\u0647 \u0627\u0632\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0627\u06cc\u0646\u200c\u0686\u0646\u06cc\u0646\u06cc\u060c \u0686\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0633\u062a \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639\u060c \u0627\u0644\u200c\u062c\u06cc \u0639\u0645\u06cc\u0642\u200c\u062a\u0631 \u0628\u0647 \u0686\u06af\u0648\u0646\u06af\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u0632\u0646\u062f\u06af\u06cc\u200c \u0631\u0648\u0632\u0645\u0631\u0647 \u062f\u0631 \u0639\u0635\u0631 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0627\u0633\u062a. \u0628\u0627 \u062a\u062c\u0645\u06cc\u0639 \u0646\u0638\u0631\u0627\u062a \u06f8\u06f5\u06f7 \u0645\u0627\u0644\u06a9 \u062e\u0627\u0646\u0647 \u0647\u0648\u0634\u0645\u0646\u062f \u062f\u0631 \u0627\u06cc\u0627\u0644\u0627\u062a\u200c\u0645\u062a\u062d\u062f\u0647\u060c \u06af\u0632\u0627\u0631\u0634 LG ThinQ 2021 Smart Home Report \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0627\u06cc\u062f\u0647\u200c\u0622\u0644 \u0628\u0631\u0627\u06cc \u0647\u0645\u06af\u0627\u0646 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<p>\u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u062f\u0627\u0631\u06a9 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647<br \/>\n\u0628\u0631\u062e\u0644\u0627\u0641 \u0622\u0646\u0686\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u062a\u0635\u0648\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u062f\u0631\u0648\u0627\u0642\u0639 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646\u06cc \u06a9\u0647 \u06a9\u0645\u062a\u0631 \u0628\u0647 \u0627\u0645\u0648\u0631 \u0641\u0646\u06cc \u062a\u0633\u0644\u0637 \u062f\u0627\u0631\u0646\u062f\u060c \u0631\u0636\u0627\u06cc\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0632 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062e\u0648\u062f\u062f\u0627\u0631\u0646\u062f. \u062a\u0639\u062f\u0627\u062f \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0633\u0646\u06cc\u0646 \u06f5\u06f0 \u062a\u0627 \u06f5\u06f4 \u0633\u0627\u0644 \u06a9\u0647 \u06af\u0641\u062a\u0647\u200c\u0627\u0646\u062f \u0627\u0632 \u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u00ab\u0631\u0636\u0627\u06cc\u062a \u06a9\u0627\u0645\u0644\u00bb \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u06cc\u0634 \u0627\u0632 \u062f\u0648 \u0628\u0631\u0627\u0628\u0631 (\u06f6\u06f0 \u062f\u0631\u0635\u062f) \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u06af\u0631\u0648\u0647 \u06f2\u06f5 \u062a\u0627 \u06f2\u06f9 \u0633\u0627\u0644 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a. \u0631\u0636\u0627\u06cc\u062a\u200c\u0645\u0646\u062f\u06cc \u0635\u0627\u062d\u0628\u200c\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u0633\u0646 \u0628\u0627\u0644\u0627\u062a\u0631 \u0628\u0648\u062f\u0647\u060c \u0632\u06cc\u0631\u0627 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u06af\u0631\u0648\u0647\u200c\u0647\u0627\u06cc \u0633\u0646\u06cc \u0645\u062f\u062a\u200c\u0632\u0645\u0627\u0646 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0648 \u06a9\u0646\u0627\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0633\u067e\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0648\u0642\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0644\u0630\u062a \u0648\u0627\u0641\u06cc \u0627\u0632 \u062a\u0645\u0627\u0645\u06cc \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062f\u0627\u0631\u0646\u062f. \u06cc\u06a9 \u0645\u0632\u06cc\u062a \u062f\u06cc\u06af\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0633\u0627\u0632\u06af\u0627\u0631 \u0648 \u06a9\u0627\u0631\u0628\u0631\u06cc \u0622\u0633\u0627\u0646\u06cc \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0645\u06af\u0627\u0646 \u0635\u0631\u0641\u200c\u0646\u0638\u0631 \u0627\u0632 \u062a\u0633\u0644\u0637 \u0641\u0646\u06cc \u06cc\u0627 \u0633\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f \u0648 \u0627\u06cc\u0646 \u06af\u0631\u0648\u0647\u200c\u0647\u0627 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u062f\u0631 \u06a9\u0627\u0647\u0634 \u0634\u06a9\u0627\u0641 \u062f\u06cc\u062c\u06cc\u062a\u0627\u0644\u06cc \u0628\u06cc\u0646 \u0646\u0633\u0644\u200c\u0647\u0627 \u0627\u06cc\u0641\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<p>\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u067e\u0630\u06cc\u0631 \u0628\u0627 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f<br \/>\n\u062f\u0631\u062d\u0627\u0644\u06cc\u200c\u06a9\u0647 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0647\u200c\u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u0637\u0631\u0627\u062d\u06cc\u200c\u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u0645\u0641\u06cc\u062f \u0648\u0627\u0642\u0639 \u0634\u0648\u0646\u062f\u060c \u0645\u0648\u0636\u0648\u0639 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u062f\u0631 \u062e\u0635\u0648\u0635 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631\u0627\u06cc \u0647\u0631 \u0641\u0631\u062f\u06cc \u0628\u0647 \u0634\u06a9\u0644\u06cc \u0645\u0646\u062d\u0635\u0631\u0628\u0647\u200c\u0641\u0631\u062f \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0638\u0631\u0633\u0646\u062c\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0641\u0636\u0627\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0646\u0639\u0637\u0641\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0631\u0632\u0634\u200c\u0647\u0627\u060c \u0639\u0644\u0627\u06cc\u0642 \u0648 \u0633\u0631\u06af\u0631\u0645\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0628\u0627 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc\u200c\u0647\u0627\u06cc \u0645\u062a\u0645\u0627\u06cc\u0632 \u0633\u0627\u0632\u06af\u0627\u0631 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0648\u0642\u062a\u06cc \u0635\u062d\u0628\u062a \u0627\u0632 \u0627\u0648\u0642\u0627\u062a \u0641\u0631\u0627\u063a\u062a \u0627\u0633\u062a\u060c \u0634\u0631\u06a9\u062a\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062f\u0631 \u0646\u0638\u0631\u0633\u0646\u062c\u06cc \u06a9\u0647 \u0639\u0644\u0627\u0642\u0647 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0647 \u0628\u0627\u063a\u0628\u0627\u0646\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0633\u06cc\u0633\u062a\u0645 \u06a9\u0646\u062a\u0631\u0644 \u0627\u0632 \u0631\u0627\u0647 \u062f\u0648\u0631 \u0648 \u0641\u0631\u0645\u0627\u0646 \u0635\u0648\u062a\u06cc \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u060c \u0645\u0627\u0634\u06cc\u0646\u200c\u0647\u0627\u06cc \u0644\u0628\u0627\u0633\u0634\u0648\u06cc\u06cc \u0648 \u06cc\u062e\u0686\u0627\u0644\u200c\u0647\u0627 \u0631\u0627 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062e\u0627\u0646\u0647 \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0631\u0634\u0645\u0631\u062f\u0646\u062f\u060c \u0632\u06cc\u0631\u0627\u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u062d\u062a\u06cc \u0647\u0646\u06af\u0627\u0645\u06cc\u200c\u06a9\u0647 \u062f\u0631 \u0628\u0627\u063a\u0686\u0647 \u0647\u0633\u062a\u0646\u062f \u0646\u06cc\u0632 \u0628\u0627 \u0644\u0648\u0627\u0632\u0645\u200c\u062e\u0627\u0646\u06af\u06cc \u062e\u0648\u062f \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u06af\u0634\u0648\u062f\u0646 \u0645\u0633\u06cc\u0631\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0631\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc \u067e\u0627\u06cc\u062f\u0627\u0631<br \/>\n\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u0645\u0631\u0648\u0632\u06cc \u0645\u0639\u06cc\u0627\u0631 \u062a\u0627\u0632\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u062f\u0648\u0633\u062a\u062f\u0627\u0631 \u0645\u062d\u06cc\u0637\u200c\u0632\u06cc\u0633\u062a \u062a\u0639\u06cc\u06cc\u0646 \u0646\u0645\u0648\u062f\u0647\u200c\u0627\u0646\u062f. \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0641\u0647\u0631\u0633\u062a \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u0632\u0627\u06cc\u0627\u06cc \u062e\u0627\u0646\u0647 \u0647\u0648\u0634\u0645\u0646\u062f\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0627\u0646\u062a\u062e\u0627\u0628 \u0634\u0631\u06a9\u062a\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0638\u0631\u0633\u0646\u062c\u06cc\u060c \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0627\u0646\u0631\u0698\u06cc \u0628\u0648\u062f\u0647 \u0627\u0633\u062a. \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0628\u0647\u06cc\u0646\u0647\u200c\u0633\u0627\u0632\u06cc \u0627\u0646\u0631\u0698\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u062c\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u062a\u0635\u0644\u060c \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0647 \u0634\u06cc\u0648\u0647 \u067e\u0627\u06cc\u062f\u0627\u0631\u062a\u0631\u06cc \u0627\u0632 \u0632\u0646\u062f\u06af\u06cc \u062f\u0633\u062a \u06cc\u0627\u0628\u0646\u062f \u0648 \u0627\u0644\u0628\u062a\u0647 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0631\u0627 \u0627\u0632 \u0635\u062f\u0648\u0631 \u0642\u0628\u0636\u200c\u0647\u0627\u06cc \u0627\u0646\u0631\u0698\u06cc \u0633\u0646\u06af\u06cc\u0646 \u062f\u0631 \u0627\u0645\u0627\u0646 \u0646\u06af\u0627\u0647 \u0645\u06cc \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p>\u06af\u0632\u0627\u0631\u0634 LG ThinQ Smart Home Report \u0646\u06af\u0627\u0647 \u062c\u0627\u0644\u0628\u06cc \u0628\u0647 \u0634\u06cc\u0648\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0637\u06cc \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u062f\u0627\u0631\u062f\u060c \u0646\u0642\u0634\u0647 \u0631\u0627\u0647\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062f\u0631 \u0632\u0646\u062f\u06af\u06cc \u0631\u0648\u0632\u0645\u0631\u0647 \u0639\u0644\u0627\u0642\u0647 \u062f\u0627\u0631\u0646\u062f. \u0628\u0631\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u06af\u0632\u0627\u0631\u0634 \u06a9\u0627\u0645\u0644 \u0627\u06cc\u0646\u062c\u0627 (https:\/\/www.lg.com\/us\/lg-thinq\/news) \u06a9\u0644\u06cc\u062f \u06a9\u0646\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc :\u0627\u06a9\u0646\u0648\u0646 \u0628\u0647\u200c\u062c\u0627\u06cc\u06cc \u0631\u0633\u06cc\u062f\u0647\u200c\u0627\u06cc\u0645 \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u062e\u0628\u0631\u06cc \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u06cc\u200c\u0647\u0627 \u0648 \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u06a9\u0647 \u0642\u0627\u062f\u0631 \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631 \u0639\u0645\u06cc\u0642 \u062f\u0631 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0627\u0646\u0633\u0627\u0646 \u0628\u0627\u0634\u0646\u062f \u0646\u06cc\u0633\u062a. \u0627\u06af\u0631\u0686\u0647 \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0628\u0647 \u0637\u0648\u0631 \u062c\u062f\u06cc \u062a\u0648\u0633\u0637 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0635\u0644\u06cc \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u0646\u062f\u060c \u0627\u0645\u0627 \u0647\u0646\u0648\u0632 \u0645\u0634\u062e\u0635 \u0646\u06cc\u0633\u062a \u06a9\u0647 \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u062f\u0631\u0648\u0627\u0642\u0639 \u0628\u0647 \u0627\u0632\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0627\u06cc\u0646\u200c\u0686\u0646\u06cc\u0646\u06cc\u060c \u0686\u0647 \u0645\u0632\u0627\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u062f\u0633\u062a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":53795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[167],"tags":[],"class_list":["post-53794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-167"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/53794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=53794"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/53794\/revisions"}],"predecessor-version":[{"id":53796,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/53794\/revisions\/53796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/53795"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=53794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=53794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=53794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}