{"id":35338,"date":"2020-12-29T20:59:10","date_gmt":"2020-12-29T21:59:10","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=35338"},"modified":"2020-12-29T20:59:10","modified_gmt":"2020-12-29T21:59:10","slug":"%d8%a8%d9%88%d8%b1%d8%b3-%da%a9%d8%a7%d9%84%d8%a7-%d9%85%db%8c%d8%b2%d8%a8%d8%a7%d9%86-%d8%b9%d8%b1%d8%b6%d9%87-%db%b2%db%b1%db%b0-%d9%87%d8%b2%d8%a7%d8%b1-%d8%aa%d9%86-%d9%81%d9%88%d9%84%d8%a7%d8%af","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/35338","title":{"rendered":"\u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0639\u0631\u0636\u0647 \u06f2\u06f1\u06f0 \u0647\u0632\u0627\u0631 \u062a\u0646 \u0641\u0648\u0644\u0627\u062f"},"content":{"rendered":"<p>\n\u062a\u0627\u0644\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648 \u0645\u0639\u062f\u0646\u06cc \u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0627\u0645\u0631\u0648\u0632 \u0633\u0647 \u0634\u0646\u0628\u0647 \u06f9 \u062f\u06cc \u0645\u0627\u0647 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0639\u0631\u0636\u0647 \u06f1\u06f3\u06f4 \u0647\u0632\u0627\u0631 \u0648 \u06f3\u06f5\u06f2 \u062a\u0646 \u0634\u0645\u0634 \u0628\u0644\u0648\u0645\u060c \u06f2\u06f0\u06f0 \u062a\u0646 \u0634\u0645\u0634 \u0686\u062f\u0646\u060c \u06f3 \u0647\u0632\u0627\u0631 \u062a\u0646 \u0648\u0631\u0642 \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647\u060c \u06f3\u06f5 \u0647\u0632\u0627\u0631 \u062a\u0646 \u062a\u062e\u062a\u0627\u0644 C \u0648 \u06f3\u06f8 \u0647\u0632\u0627\u0631 \u062a\u0646 \u062a\u062e\u062a\u0627\u0644 SM \u0627\u0633\u062a. <\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632  \u00ab\u06a9\u0627\u0644\u0627\u062e\u0628\u0631\u00bb\u061b \u06f4\u06f3\u06f0 \u062a\u0646 \u0634\u0645\u0634 \u0631\u0648\u06cc\u060c \u06f1\u06f5 \u062a\u0646 \u06a9\u0646\u0633\u0627\u0646\u062a\u0631\u0647 \u0641\u0644\u0632\u0627\u062a \u06af\u0631\u0627\u0646\u0628\u0647\u0627 \u0648 \u06f1\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645 \u0634\u0645\u0634 \u0637\u0644\u0627 \u0646\u06cc\u0632 \u062f\u0631 \u062a\u0627\u0644\u0627\u0631 \u0645\u0630\u06a9\u0648\u0631 \u0639\u0631\u0636\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u062a\u0627\u0644\u0627\u0631 \u0641\u0631\u0622\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u0646\u0641\u062a\u06cc \u0648 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0632 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0639\u0631\u0636\u0647 \u06f5\u06f1 \u0647\u0632\u0627\u0631 \u0648 \u06f4\u06f1\u06f4 \u062a\u0646 \u0645\u0648\u0627\u062f \u067e\u0644\u06cc\u0645\u0631\u06cc\u060c \u06f3 \u0647\u0632\u0627\u0631 \u062a\u0646 \u0633\u0644\u0627\u067e\u0633 \u0648\u0627\u06a9\u0633\u060c \u06f3 \u0647\u0632\u0627\u0631 \u0648 \u06f6\u06f3\u06f0 \u062a\u0646 \u0642\u06cc\u0631\u060c \u06cc\u06a9 \u0647\u0632\u0627\u0631 \u062a\u0646 \u06af\u0648\u06af\u0631\u062f \u0648 \u06f5\u06f3 \u0647\u0632\u0627\u0631 \u062a\u0646 \u0648\u06a9\u06cc\u0648\u0645 \u0628\u0627\u062a\u0648\u0645 \u0627\u0633\u062a.<\/p>\n<p>\u062a\u0627\u0644\u0627\u0631 \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0646\u06cc\u0632 \u0634\u0627\u0647\u062f \u0639\u0631\u0636\u0647 \u06f5\u06f4 \u0647\u0632\u0627\u0631 \u0648 \u06f5\u06f0\u06f0 \u062a\u0646 \u0642\u06cc\u0631 \u0627\u0633\u062a.<\/p>\n<p>\u062a\u0627\u0644\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0639\u0631\u0636\u0647 \u06f4\u06f6\u06f0 \u06a9\u06cc\u0644\u0648\u06af\u0631\u0645 \u0632\u0639\u0641\u0631\u0627\u0646 \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0648 \u06f6\u06f1\u06f0 \u062a\u0646 \u062e\u0631\u0645\u0627\u06cc \u0627\u0633\u062a\u0639\u0645\u0631\u0627\u0646 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc \u06a9\u0646\u062f. <\/p>\n<p>\u0628\u0627\u0632\u0627\u0631 \u0641\u0631\u0639\u06cc \u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0632 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0639\u0631\u0636\u0647 \u06f1\u06f2\u06f0 \u062a\u0646 \u062f\u0648\u062f\u0647 \u0635\u0646\u0639\u062a\u06cc \u0648 \u06f7\u06f0\u06f0 \u062a\u0646 \u0636\u0627\u06cc\u0639\u0627\u062a \u0641\u0648\u0644\u0627\u062f\u06cc \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u0627\u0644\u0627\u0631 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0635\u0646\u0639\u062a\u06cc \u0648 \u0645\u0639\u062f\u0646\u06cc \u0628\u0648\u0631\u0633 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0627\u0645\u0631\u0648\u0632 \u0633\u0647 \u0634\u0646\u0628\u0647 \u06f9 \u062f\u06cc \u0645\u0627\u0647 \u0645\u06cc\u0632\u0628\u0627\u0646 \u0639\u0631\u0636\u0647 \u06f1\u06f3\u06f4 \u0647\u0632\u0627\u0631 \u0648 \u06f3\u06f5\u06f2 \u062a\u0646 \u0634\u0645\u0634 \u0628\u0644\u0648\u0645\u060c \u06f2\u06f0\u06f0 \u062a\u0646 \u0634\u0645\u0634 \u0686\u062f\u0646\u060c \u06f3 \u0647\u0632\u0627\u0631 \u062a\u0646 \u0648\u0631\u0642 \u06af\u0627\u0644\u0648\u0627\u0646\u06cc\u0632\u0647\u060c \u06f3\u06f5 \u0647\u0632\u0627\u0631 \u062a\u0646 \u062a\u062e\u062a\u0627\u0644 C \u0648 \u06f3\u06f8 \u0647\u0632\u0627\u0631 \u062a\u0646 \u062a\u062e\u062a\u0627\u0644 SM \u0627\u0633\u062a. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u00ab\u06a9\u0627\u0644\u0627\u062e\u0628\u0631\u00bb\u061b \u06f4\u06f3\u06f0 \u062a\u0646 \u0634\u0645\u0634 \u0631\u0648\u06cc\u060c [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":35339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-35338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-17"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/35338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=35338"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/35338\/revisions"}],"predecessor-version":[{"id":35340,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/35338\/revisions\/35340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/35339"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=35338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=35338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=35338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}