{"id":21591,"date":"2020-07-22T21:22:23","date_gmt":"2020-07-22T21:22:23","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=21591"},"modified":"2020-07-22T21:22:23","modified_gmt":"2020-07-22T21:22:23","slug":"%d9%81%d8%b9%d8%a7%d9%84%db%8c%d8%aa-%d9%87%d8%a7%db%8c-%d9%85%d8%ac%d8%af%d8%af-%d8%af%d8%a7%d9%86%d8%b4%da%af%d8%a7%d9%87-%d8%a8%db%8c%d9%85%d9%87-%d8%a7%db%8c%d8%b1%d8%a7%d9%86-%d8%a8%d8%a7-%d9%87","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/21591","title":{"rendered":"\u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u0645\u062c\u062f\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0647\u0641\u062a \u0631\u0634\u062a\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0622\u063a\u0627\u0632 \u0634\u062f"},"content":{"rendered":"<p>\u067e\u0633 \u0627\u0632 \u06f8 \u0645\u0627\u0647 \u062a\u0644\u0627\u0634 \u0645\u0633\u062a\u0645\u0631 \u0648 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0627\u062a \u0645\u06a9\u0631\u0631 \u0628\u0627 \u0645\u0633\u0626\u0648\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062c\u0627\u0645\u0639 \u0639\u0644\u0645\u06cc \u200f\u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u06f2\u06f5 \u062a\u06cc\u0631 \u06f9\u06f9 \u062f\u0631 \u0647\u0641\u062a \u0631\u0634\u062a\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0648 \u200f\u062f\u0631 \u0645\u0642\u0627\u0637\u0639 \u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u0648 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062d\u06cc\u0627\u0621 \u0634\u062f \u0648 \u0627\u0632 \u0645\u0647\u0631 \u0645\u0633\u0627\u0644 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u06a9\u0646\u06a9\u0648\u0631 \u0633\u0631\u0627\u0633\u0631\u06cc \u200f\u0646\u0633\u0628\u062a \u0628\u0647 \u062c\u0630\u0628 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u0627\u0646 \u0627\u0642\u062f\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f.\u200f<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc  \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646\u060c \u062d\u0645\u06cc\u062f \u0645\u0639\u06cc\u0646\u06cc \u0645\u0634\u0627\u0648\u0631 \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u200f\u0648 \u0633\u0631\u067e\u0631\u0633\u062a \u0645\u0631\u06a9\u0632 \u0622\u0645\u0648\u0632\u0634 \u0639\u0644\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0627\u0646\u062a\u0634\u0627\u0631 \u06af\u0632\u0627\u0631\u0634\u06cc \u0627\u0632 \u0631\u0648\u0646\u062f \u062a\u0648\u0642\u0641 \u0648 \u0627\u062d\u06cc\u0627\u06cc \u0645\u062c\u062f\u062f \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0646\u0648\u0634\u062a: \u0639\u0644\u06cc\u0631\u063a\u0645 \u062a\u0645\u0627\u0645\u06cc \u062a\u0644\u0627\u0634 \u0647\u0627\u06cc \u0647\u0634\u062a \u0645\u0627\u0647\u0647 \u062f\u0631 \u0627\u062e\u0630 \u0645\u062c\u0648\u0632 \u0627\u062f\u0627\u0645\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062f\u0631 \u0645\u062f\u062a \u0645\u0642\u0631\u0631 \u062f\u0648\u0633\u0627\u0644\u0647 ( \u06f3\u06f0\u200f\/\u06f7\u200f\/\u06f9\u06f6 \u062a\u0627 \u200f\u200f\u06f3\u06f0\u200f\/\u06f7\u200f\/\u06f9\u06f8 \u200f\u200f) \u0627\u0645\u06a9\u0627\u0646 \u067e\u0630\u06cc\u0631 \u0646\u0634\u062f \u0648 \u0632\u0645\u0627\u0646 \u0648 \u0645\u0647\u0644\u062a \u0645\u0642\u0631\u0631 \u06a9\u0627\u0645\u0644\u0622 \u0628\u0647 \u067e\u0627\u06cc\u0627\u0646 \u0631\u0633\u06cc\u062f \u0648 \u0639\u0645\u0644\u0627 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0647\u06cc\u0686 \u200f\u0645\u062c\u0648\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a \u0642\u0627\u0646\u0648\u0646\u06cc \u0628\u0631\u0627\u06cc \u200f\u0627\u062f\u0627\u0645\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u0646\u062f\u0627\u0634\u062a. \u0644\u06cc\u06a9\u0646 \u0628\u0647 \u062c\u0647\u062a \u0627\u0639\u062a\u0642\u0627\u062f \u0648 \u0628\u0627\u0648\u0631 \u0622\u0642\u0627\u06cc \u062f\u06a9\u062a\u0631 \u200f\u0631\u0636\u0627\u06cc\u06cc \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0645\u062d\u062a\u0631\u0645 \u0634\u0631\u06a9\u062a \u0648 \u200f\u0627\u0646\u062a\u0635\u0627\u0628 \u0631\u06cc\u0627\u0633\u062a \u062c\u062f\u06cc\u062f \u062f\u0627\u0646\u0634\u06af\u0627\u0647 [\u062f\u06a9\u062a\u0631 \u0645\u0639\u06cc\u0646\u06cc]\u060c \u0647\u0645\u062a \u0648 \u200f\u062c\u062f\u06cc\u062a \u0627\u06cc\u0634\u0627\u0646 \u062f\u0631 \u067e\u06cc\u0634\u0628\u0631\u062f \u0627\u0645\u0648\u0631 \u062a\u0627 \u062d\u0635\u0648\u0644 \u0646\u062a\u06cc\u062c\u0647 \u0646\u0647\u0627\u06cc\u06cc \u200f\u0628\u0647 \u0628\u0627\u0631 \u0646\u0634\u0633\u062a \u0648 \u067e\u0633 \u0627\u0632 \u06f8 \u0645\u0627\u0647 \u062a\u0644\u0627\u0634 \u0645\u0633\u062a\u0645\u0631 \u0648 \u200f\u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0627\u062a \u0645\u06a9\u0631\u0631 \u0628\u0627 \u0645\u0633\u0626\u0648\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062c\u0627\u0645\u0639 \u0639\u0644\u0645\u06cc \u200f\u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u0645\u0648\u062c\u0628 \u0627\u0628\u0644\u0627\u063a\u06cc\u0647 \u0645\u0648\u0631\u062e \u06f2\u06f5\/\u06f4\/\u06f1\u06f3\u06f9\u06f9 \u062f\u0631 \u0647\u0641\u062a \u0631\u0634\u062a\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0648 \u200f\u062f\u0631 \u0645\u0642\u0627\u0637\u0639 \u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u0648 \u200f\u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062d\u06cc\u0627\u0621 \u0634\u062f \u0648 \u0627\u0632 \u0645\u0647\u0631 \u0627\u0645\u0633\u0627\u0644 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u06a9\u0646\u06a9\u0648\u0631 \u0633\u0631\u0627\u0633\u0631\u06cc \u200f\u0646\u0633\u0628\u062a \u0628\u0647 \u200f\u062c\u0630\u0628 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u0627\u0646 \u0627\u0642\u062f\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f.\u200f<\/p>\n<p>\u0631\u0634\u062a\u0647 \u0647\u0627\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0648 \u0645\u0642\u0627\u0637\u0639\u06cc \u06a9\u0647 \u0645\u0631\u06a9\u0632 \u0622\u0645\u0648\u0632\u0634 \u0639\u0644\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0632\u0645\u0648\u0646 \u0633\u0631\u0627\u0633\u0631\u06cc \u06a9\u0646\u06a9\u0648\u0631 \u06f9\u06f9 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u062c\u0630\u0628 \u062f\u0627\u0646\u0634\u062c\u0648 \u062e\u0648\u0627\u0647\u062f \u06a9\u0631\u062f\u060c \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632: \u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0627\u0645\u0648\u0631\u0628\u06cc\u0645\u0647\u060c\u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc\u060c \u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u062d\u0633\u0627\u0628\u062f\u0627\u0631\u06cc \u0634\u0631\u06a9\u062a \u0647\u0627\u06cc \u0628\u06cc\u0645\u0647\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0627\u0632\u0627\u0631\u06cc\u0627\u0628\u06cc \u0628\u06cc\u0645\u0647\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u06cc\u0645\u0647 \u200f- \u0628\u06cc\u0645\u0647 \u0627\u0634\u062e\u0627\u0635\u060c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u06cc\u0645\u0647 \u200f- \u0628\u06cc\u0645\u0647 \u0627\u0645\u0648\u0627\u0644 \u0648 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u062d\u0642\u0648\u0642 \u0628\u06cc\u0645\u0647<\/p>\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a: \u0645\u0631\u06a9\u0632 \u0622\u0645\u0648\u0632\u0634 \u0639\u0644\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0648\u0627\u0628\u0633\u062a\u0647 \u0628\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062c\u0627\u0645\u0639 \u0639\u0644\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0627\u0632 \u0633\u0627\u0644 \u06f1\u06f3\u06f9\u06f0 \u0628\u0627 \u0641\u0631\u0627\u0632 \u0648 \u200f\u0641\u0631\u0648\u062f\u0647\u0627\u06cc\u06cc \u0647\u0645\u0631\u0627\u0647 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a . \u062a\u0627\u0633\u06cc\u0633 \u0627\u06cc\u0646 \u0645\u0631\u06a9\u0632 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u062e\u0648\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u06a9 \u062a\u0631\u06cc\u0646 \u062a\u0635\u0645\u06cc\u0645 \u200f\u062f\u0631 \u0646\u0648\u0639 \u062e\u0648\u062f \u0628\u0648\u062f \u0627\u0632 \u0622\u0646 \u0632\u0645\u0627\u0646 \u062a\u0627\u06a9\u0646\u0648\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06af\u0627\u0646\u0647 \u0645\u0631\u06a9\u0632 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a \u0628\u06cc\u0645\u0647 \u0628\u0627\u0642\u06cc \u0645\u0627\u0646\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0628\u0647 \u062d\u0642 \u0648 \u200f\u0634\u0627\u06cc\u0633\u062a\u0647 \u0628\u0648\u062f \u06a9\u0647 \u0634\u0631\u06a9\u062a \u0633\u0647\u0627\u0645\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u067e\u0627\u06cc\u0647 \u06af\u0630\u0627\u0631 \u0635\u0646\u0639\u062a \u0628\u06cc\u0645\u0647 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0648 \u0628\u0632\u0631\u06af\u062a\u0631\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0628\u06cc\u0645\u0647 \u062f\u0631 \u200f\u0645\u0646\u0637\u0642\u0647 \u062e\u0627\u0648\u0631\u0645\u06cc\u0627\u0646\u0647 \u0632\u06cc\u0628\u0646\u062f\u0647 \u0686\u0646\u06cc\u0646 \u062f\u0627\u0631\u0627\u0626\u06cc \u0627\u0631\u0632\u0634\u0645\u0646\u062f\u06cc \u0628\u0627\u0634\u062f \u0648 \u062a\u0648\u0627\u0646\u0633\u062a \u0645\u0646\u0634\u0627\u0621 \u0627\u062b\u0631\u0627\u062a \u0648 \u0628\u0631\u06a9\u0627\u062a \u0639\u0644\u0645\u06cc \u0648 \u067e\u0698\u0648\u0647\u0634\u06cc \u062f\u0631 \u200f\u0634\u0631\u06a9\u062a \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0648 \u062f\u0631 \u0645\u062c\u0645\u0648\u0639 \u0635\u0646\u0639\u062a \u0628\u06cc\u0645\u0647 \u0628\u0627\u0634\u062f \u0648 \u0628\u0627 \u067e\u0631\u0648\u0631\u0634 \u062d\u062f\u0648\u062f \u06f4\u06f0\u06f0\u06f0 \u0646\u0641\u0631 \u0641\u0627\u0631\u063a \u0627\u0644\u062a\u062d\u0635\u06cc\u0644 \u062f\u0631 \u0645\u0642\u0627\u0637\u0639 \u200f\u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u0648 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0628\u0631\u06af \u0632\u0631\u06cc\u0646\u06cc \u062f\u0631 \u0627\u0641\u062a\u062e\u0627\u0631\u0627\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0631\u0642\u0645 \u0632\u0646\u062f.<\/p>\n<p>\u0634\u0639\u0627\u0631 \u0645\u0631\u06a9\u0632 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0639\u0644\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u200f\u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627 \u0639\u0628\u0627\u0631\u062a \u0628\u0648\u062f \u0627\u0632 \u00ab\u067e\u06cc\u0634\u0631\u0648 \u062f\u0631 \u0622\u0645\u0648\u0632\u0634 \u0647\u0627\u06cc \u0622\u06a9\u0627\u062f\u0645\u06cc\u06a9 \u0635\u0646\u0639\u062a \u0628\u06cc\u0645\u0647\u00bb \u06a9\u0647 \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u062a\u0631\u0645\u06cc\u06a9 \u200f\u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc\u060c  \u0628\u0627 \u0627\u062e\u0630 \u0645\u062c\u0648\u0632 \u0627\u0632 \u0628\u06cc\u0645\u0647 \u0645\u0631\u06a9\u0632\u06cc \u0648 \u067e\u0698\u0648\u0647\u0634\u06a9\u062f\u0647 \u0628\u06cc\u0645\u0647\u060c \u0645\u062c\u0631\u06cc \u0648 \u0628\u0631\u06af\u0632\u0627\u0631\u06a9\u0646\u0646\u062f\u0647 \u062f\u0648\u0631\u0647 \u0647\u0627\u06cc \u0622\u0645\u0648\u0632\u0634 \u0622\u0632\u0627\u062f \u0627\u0632 \u200f\u062c\u0645\u0644\u0647 \u062f\u0648\u0631\u0647 \u0647\u0627\u06cc \u0622\u0645\u0648\u0632\u0634 \u062c\u0630\u0628 \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646\u060c \u0622\u0645\u0648\u0632\u0634 \u062c\u0630\u0628 \u06a9\u0627\u0631\u06af\u0632\u0627\u0631\u0627\u0646 \u0628\u06cc\u0645\u0647\u060c \u062f\u0648\u0631\u0647 \u0622\u0645\u0648\u0632\u0634 \u062c\u0630\u0628 \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646 \u0628\u06cc\u0645\u0647 \u200f\u0647\u0627\u06cc \u0632\u0646\u062f\u06af\u06cc\u060c \u062f\u0648\u0631\u0647 \u0622\u0645\u0648\u0632\u0634 \u0633\u0627\u0632\u0645\u0627\u0646 \u0641\u0631\u0648\u0634 \u0648 \u0633\u0627\u06cc\u0631 \u0622\u0632\u0645\u0648\u0646 \u0647\u0627 \u0648 \u0645\u0635\u0627\u062d\u0628\u0647 \u0647\u0627\u06cc \u062d\u0636\u0648\u0631\u06cc \u062c\u0630\u0628 \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646 \u062c\u0646\u0631\u0627\u0644 \u0648 \u200f\u062f\u0648\u0631\u0647 \u0647\u0627\u06cc\u200e MBA \u200e\u0628\u06cc\u0645\u0647 \u0627\u06cc\u060c \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u067e\u0698\u0648\u0647\u0634\u06cc \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u0639\u0644\u0645\u06cc \u062f\u06cc\u06af\u0631 \u0648 \u0686\u0634\u0645 \u0648 \u0686\u0631\u0627\u063a \u200f\u0635\u0646\u0639\u062a \u0628\u06cc\u0645\u0647 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0627\u0645\u06cc\u062f \u062f\u0627\u0631\u06cc\u0645 \u0627\u0646 \u0634\u0627\u0621 \u0627\u0644\u0644\u0647 \u0628\u0627 \u062a\u062c\u062f\u06cc\u062f \u062d\u06cc\u0627\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u062a\u06a9\u0644\u06cc\u0641 \u0648 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u062e\u0637\u06cc\u0631\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u0645\u0631 \u0622\u0645\u0648\u0632\u0634 \u0648 \u067e\u0698\u0648\u0647\u0634 \u200f\u0628\u0631\u062f\u0648\u0634 \u0627\u06cc\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0648 \u0634\u0631\u06a9\u062a \u0633\u0647\u0627\u0645\u06cc \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0642\u0631\u0627\u0631\u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a \u06a9\u0645\u0627\u0641\u06cc \u0627\u0644\u0633\u0627\u0628\u0642 \u0628\u0647 \u0646\u062d\u0648 \u0627\u062d\u0633\u0646 \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f \u0648 \u0628\u0647 \u200f\u0622\u0645\u0627\u0644 \u0647\u0627 \u0648 \u0622\u0631\u0632\u0648\u0647\u0627 \u062f\u0631 \u062a\u0631\u0628\u06cc\u062a \u0648 \u067e\u0631\u0648\u0631\u0634 \u0646\u06cc\u0631\u0648\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc \u0628\u0627 \u062f\u0627\u0646\u0634 \u0648 \u0645\u0642\u062a\u062f\u0631 \u0628\u0631\u0627\u06cc \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u0627\u0647\u062f\u0627\u0641 \u0639\u0627\u0644\u06cc\u0647 \u0648 \u0645\u0646\u0648\u06cc\u0627\u062a \u200f\u0645\u0642\u0627\u0645 \u0645\u0639\u0638\u0645 \u0631\u0647\u0628\u0631\u06cc \u062f\u0631 \u0633\u0627\u0644 \u062c\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062f\u0633\u062a\u06cc\u0627\u0628\u06cc \u0628\u0647 \u0636\u0631\u06cc\u0628 \u0646\u0641\u0648\u0630 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0633\u0637\u062d \u0645\u0646\u0637\u0642\u0647 \u0627\u06cc \u0648 \u062c\u0647\u0627\u0646\u06cc \u0646\u0627\u06cc\u0644 \u200f\u0634\u0648\u06cc\u0645.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u067e\u0633 \u0627\u0632 \u06f8 \u0645\u0627\u0647 \u062a\u0644\u0627\u0634 \u0645\u0633\u062a\u0645\u0631 \u0648 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0627\u062a \u0645\u06a9\u0631\u0631 \u0628\u0627 \u0645\u0633\u0626\u0648\u0644\u0627\u0646 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u062c\u0627\u0645\u0639 \u0639\u0644\u0645\u06cc \u200f\u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c \u0641\u0639\u0627\u0644\u06cc\u062a \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0628\u06cc\u0645\u0647 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0632 \u06f2\u06f5 \u062a\u06cc\u0631 \u06f9\u06f9 \u062f\u0631 \u0647\u0641\u062a \u0631\u0634\u062a\u0647 \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0648 \u200f\u062f\u0631 \u0645\u0642\u0627\u0637\u0639 \u06a9\u0627\u0631\u062f\u0627\u0646\u06cc \u0648 \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u06cc \u0627\u062d\u06cc\u0627\u0621 \u0634\u062f \u0648 \u0627\u0632 \u0645\u0647\u0631 \u0645\u0633\u0627\u0644 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u06a9\u0646\u06a9\u0648\u0631 \u0633\u0631\u0627\u0633\u0631\u06cc \u200f\u0646\u0633\u0628\u062a \u0628\u0647 \u062c\u0630\u0628 \u062f\u0627\u0646\u0634\u062c\u0648\u06cc\u0627\u0646 \u0627\u0642\u062f\u0627\u0645 \u0645\u06cc \u0634\u0648\u062f.\u200f \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-21591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/21591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=21591"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/21591\/revisions"}],"predecessor-version":[{"id":21593,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/21591\/revisions\/21593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/21592"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=21591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=21591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=21591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}