{"id":121041,"date":"2025-01-27T08:08:50","date_gmt":"2025-01-27T09:08:50","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=121041"},"modified":"2025-02-05T08:09:29","modified_gmt":"2025-02-05T09:09:29","slug":"%d8%aa%d8%ad%d9%82%d9%82-%d8%aa%d8%ad%d9%88%d9%84%db%8c-%d9%86%d9%88-%d8%af%d8%b1-%d9%be%d8%aa%d8%b1%d9%88%d8%b4%db%8c%d9%85%db%8c-%d9%81%d9%86%e2%80%8c%d8%a2%d9%88%d8%b1%d8%a7%d9%86%d8%9b-%da%af","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/121041","title":{"rendered":"\u062a\u062d\u0642\u0642 \u062a\u062d\u0648\u0644\u06cc \u0646\u0648 \u062f\u0631 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646\u061b \u06af\u0632\u0627\u0631\u0634 \u0634\u06af\u0641\u062a\u200c\u0627\u0646\u06af\u06cc\u0632 \u06f1\u06f0 \u0645\u0627\u0647\u0647 \u0634\u0641\u0646 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f"},"content":{"rendered":"<p> \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u06f1\u06f0 \u0645\u0627\u0647 \u0646\u062e\u0633\u062a \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f3 \u062a\u0648\u0627\u0646\u0633\u062a \u0631\u06a9\u0648\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u200c\u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0633\u0648\u062f\u0622\u0648\u0631\u06cc \u0648 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062b\u0628\u062a \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0645\u0648\u0641\u0642 \u0634\u062f \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f1\u06f2\u06f1\u06f0 \u062f\u0631\u0635\u062f\u06cc \u0633\u0648\u062f \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0647\u0631 \u0633\u0647\u0645 \u0648 \u06f1\u06f1\u06f1\u06f6 \u062f\u0631\u0635\u062f\u06cc \u0633\u0648\u062f \u062e\u0627\u0644\u0635 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0644 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0631\u0634\u062f \u0631\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f \u0648 \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f4\u06f4 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u06f1\u06f0 \u0645\u0627\u0647\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062d\u062c\u0645 \u062a\u0648\u0644\u06cc\u062f \u0648 \u0635\u0627\u062f\u0631\u0627\u062a\u060c \u0628\u0647 \u0627\u0633\u062a\u0642\u0628\u0627\u0644 \u0627\u0641\u062a\u062a\u0627\u062d\u06cc\u0647 \u0648 \u0622\u063a\u0627\u0632 \u0639\u0645\u0644\u06cc\u0627\u062a \u0627\u062c\u0631\u0627\u06cc\u06cc \u067e\u0631\u0648\u0698\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u062e\u0648\u062f \u0631\u0648\u062f \u062a\u0627 \u0622\u063a\u0627\u0632 \u0641\u0635\u0644 \u0646\u0648 \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0645\u062d\u0642\u0642 \u0634\u0648\u062f.<br \/>\n\u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc : \u0628\u0631 \u067e\u0627\u06cc\u0647 \u06af\u0632\u0627\u0631\u0634 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f\u0647 \u0634\u0641\u0646 \u062f\u0631 \u06a9\u062f\u0627\u0644\u060c \u062f\u0631\u0622\u0645\u062f \u0639\u0645\u0644\u06cc\u0627\u062a\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u062f\u06cc\u200c\u0645\u0627\u0647 \u0628\u0647 \u06f1\u06f1\u06f9.\u06f0\u06f3\u06f3.\u06f3\u06f9\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0631\u06cc\u0627\u0644 (\u06f1\u06f1.\u06f9 \u0647\u0645\u062a) \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0642\u0645\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u06f8\u06f2.\u06f8\u06f9\u06f7.\u06f5\u06f9\u06f8 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0631\u06cc\u0627\u0644 \u0645\u062f\u062a \u0645\u0634\u0627\u0628\u0647 \u0633\u0627\u0644 \u0642\u0628\u0644\u060c \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0631\u0634\u062f \u0642\u0648\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f4\u06f4 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0627\u062e\u0635 \u06a9\u0644\u06cc\u062f\u06cc \u0637\u06cc \u06f1\u06f0 \u0645\u0627\u0647 \u0627\u0645\u0633\u0627\u0644 \u0646\u0633\u0628\u062a \u0628\u0647 \u06f1\u06f2 \u0645\u0627\u0647\u0647 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0627\u0633\u062a.<br \/>\n\u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u060c \u0628\u0647\u0628\u0648\u062f \u0627\u0633\u062a\u0631\u0627\u062a\u0698\u06cc\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0648 \u06af\u0634\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0634\u0631\u06a9\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u0631\u0633\u06cc\u062f\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0641\u0642\u06cc\u062a\u200c\u0647\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u0628\u0631 \u067e\u0627\u06cc\u0647 \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634\u060c \u062d\u062c\u0645 \u0641\u0631\u0648\u0634 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u062f\u06cc\u200c\u0645\u0627\u0647 \u06f1\u06f4\u06f0\u06f3 \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u0627\u0647 \u0645\u0634\u0627\u0628\u0647 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0628\u0627 \u06f6\u06f6 \u062f\u0631\u0635\u062f \u0631\u0634\u062f \u0628\u0647 \u06f9\u06f2.\u06f6\u06f0\u06f3 \u062a\u0646 \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062f\u0631\u0622\u0645\u062f \u062d\u0627\u0635\u0644 \u0627\u0632 \u0641\u0631\u0648\u0634 \u0627\u06cc\u0646 \u0645\u0627\u0647 \u0646\u06cc\u0632 \u0628\u0627 \u0631\u0634\u062f \u06f6\u06f6 \u062f\u0631\u0635\u062f\u06cc \u0628\u0647 \u06f1.\u06f7\u06f9 \u0647\u0632\u0627\u0631 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646 \u0631\u0633\u06cc\u062f\u0647 \u0648 \u062f\u0631 \u0628\u062e\u0634 \u0635\u0627\u062f\u0631\u0627\u062a\u060c \u062d\u062c\u0645 \u0641\u0631\u0648\u0634 \u0635\u0627\u062f\u0631\u0627\u062a\u06cc \u0628\u0627 \u06f5 \u062f\u0631\u0635\u062f \u0631\u0634\u062f \u0628\u0647 \u06f5\u06f1\u06f7.\u06f5\u06f8\u06f0 \u062a\u0646 \u0648 \u0627\u0631\u0632\u0634 \u0622\u0646 \u0627\u0632 \u06f1\u06f5\u06f0 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631 \u0641\u0631\u0627\u062a\u0631 \u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<br \/>\n\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u067e\u0631\u0648\u0698\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u0633\u0639\u0647\u200c\u0627\u06cc \u062c\u062f\u06cc\u062f \u0648 \u0628\u0647\u0631\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u0632\u0648\u062f\u06cc \u0627\u062c\u0631\u0627\u06cc\u06cc \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f\u060c \u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062f\u0631\u0622\u0645\u062f \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f3 \u0628\u0627 \u0631\u0634\u062f \u0628\u06cc\u0634\u062a\u0631\u06cc \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0627\u0644 \u0642\u0628\u0644 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u062a\u062d\u0648\u0644 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u0648\u06cc\u062f\u0628\u062e\u0634 \u0622\u06cc\u0646\u062f\u0647\u200c\u0627\u06cc \u0631\u0648\u0634\u0646 \u0648 \u062a\u0636\u0645\u06cc\u0646\u200c\u0634\u062f\u0647 \u0628\u0631\u0627\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u0644\u0627\u0632\u0645 \u0628\u0647 \u0630\u06a9\u0631 \u0627\u0633\u062a\u060c \u0633\u0648\u062f \u062e\u0627\u0644\u0635 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u0627\u06cc\u0646 \u0628\u0627\u0632\u0647 \u0632\u0645\u0627\u0646\u06cc \u0627\u0632 \u06f2.\u06f6\u06f6\u06f2.\u06f5\u06f9\u06f7 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0631\u06cc\u0627\u0644 \u062f\u0631 \u067e\u0627\u06cc\u0627\u0646 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u0628\u0647 \u06f3\u06f2.\u06f3\u06f9\u06f5.\u06f8\u06f5\u06f6 \u0645\u06cc\u0644\u06cc\u0648\u0646 \u0631\u06cc\u0627\u0644 (\u06f3.\u06f2 \u0647\u0645\u062a) \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u0645\u0627\u0647 \u0646\u062e\u0633\u062a \u0632\u0645\u0633\u062a\u0627\u0646 \u0631\u0633\u06cc\u062f\u0647 \u06a9\u0647 \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f1\u06f1\u06f1\u06f6 \u062f\u0631\u0635\u062f\u06cc \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u062f\u06cc\u0645\u0627\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0644 \u0632\u0645\u0627\u0646 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647 \u062f\u0627\u0631\u062f.<br \/>\n\u0633\u0648\u062f \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0647\u0631 \u0633\u0647\u0645 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0627\u06cc\u0646 \u06f1\u06f0 \u0645\u0627\u0647 \u0628\u0647 \u06f1.\u06f0\u06f4\u06f7 \u0631\u06cc\u0627\u0644 \u0631\u0633\u06cc\u062f\u0647 \u06a9\u0647 \u0646\u0633\u0628\u062a \u0628\u0647 \u0633\u0648\u062f \u06f8\u06f6 \u0631\u06cc\u0627\u0644\u06cc \u06f1\u06f2 \u0645\u0627\u0647\u0647 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f1\u06f2\u06f1\u06f0 \u062f\u0631\u0635\u062f\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0628\u0627\u0632\u0647 \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0627\u06cc\u0646 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631 \u062f\u0631 \u0633\u0648\u062f \u0647\u0631 \u0633\u0647\u0645\u060c \u0628\u0631\u0627\u06cc \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u0646\u0634\u0627\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u0628\u0627\u0632\u062f\u0647\u06cc \u0645\u0637\u0644\u0648\u0628 \u0648 \u067e\u0627\u06cc\u062f\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc\u0634\u0627\u0646 \u0627\u0633\u062a.<br \/>\n\u0627\u06cc\u0646 \u0631\u0634\u062f \u062f\u0631 \u0633\u0648\u062f \u0647\u0631 \u0633\u0647\u0645\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u062c\u0644\u0628 \u062a\u0648\u062c\u0647 \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646 \u0641\u0639\u0644\u06cc\u060c \u0628\u0627\u0639\u062b \u062c\u0630\u0628 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u062c\u062f\u06cc\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0628\u0648\u0631\u0633 \u0634\u062f\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631 \u0628\u0627\u0632\u062f\u0647\u06cc \u0633\u0647\u0645\u060c \u0646\u0648\u06cc\u062f\u0628\u062e\u0634 \u0686\u0634\u0645\u200c\u0627\u0646\u062f\u0627\u0632 \u0645\u062b\u0628\u062a \u0634\u0631\u06a9\u062a \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0648 \u0628\u0644\u0646\u062f\u0645\u062f\u062a \u0627\u0633\u062a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0641\u0646\u200c\u0622\u0648\u0631\u0627\u0646 \u062f\u0631 \u06f1\u06f0 \u0645\u0627\u0647 \u0646\u062e\u0633\u062a \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f3 \u062a\u0648\u0627\u0646\u0633\u062a \u0631\u06a9\u0648\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u200c\u0633\u0627\u0628\u0642\u0647\u200c\u0627\u06cc \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0633\u0648\u062f\u0622\u0648\u0631\u06cc \u0648 \u0628\u0647\u0631\u0647\u200c\u0648\u0631\u06cc \u062b\u0628\u062a \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a \u0645\u0648\u0641\u0642 \u0634\u062f \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f1\u06f2\u06f1\u06f0 \u062f\u0631\u0635\u062f\u06cc \u0633\u0648\u062f \u0628\u0631 \u067e\u0627\u06cc\u0647 \u0647\u0631 \u0633\u0647\u0645 \u0648 \u06f1\u06f1\u06f1\u06f6 \u062f\u0631\u0635\u062f\u06cc \u0633\u0648\u062f \u062e\u0627\u0644\u0635 \u0646\u0633\u0628\u062a \u0628\u0647 \u06a9\u0644 \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0631\u0634\u062f \u0631\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0647 \u062f\u0633\u062a \u0622\u0648\u0631\u062f \u0648 \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06f4\u06f4 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":121042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-121041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/121041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=121041"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/121041\/revisions"}],"predecessor-version":[{"id":121043,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/121041\/revisions\/121043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/121042"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=121041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=121041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=121041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}