{"id":118077,"date":"2024-05-22T08:21:10","date_gmt":"2024-05-22T08:21:10","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=118077"},"modified":"2024-05-22T08:21:10","modified_gmt":"2024-05-22T08:21:10","slug":"%d9%be%db%8c%d8%a7%d9%85-%d8%aa%d8%b3%d9%84%db%8c%d8%aa-%d8%a8%db%8c%d9%85%d9%87-%d8%b3%db%8c%d9%86%d8%a7-%d8%a8%d9%87-%d9%85%d9%86%d8%a7%d8%b3%d8%a8%d8%aa-%d8%b4%d9%87%d8%a7%d8%af%d8%aa-%d8%b1%db%8c","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/118077","title":{"rendered":"\u067e\u06cc\u0627\u0645 \u062a\u0633\u0644\u06cc\u062a \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627 \u0628\u0647 \u0645\u0646\u0627\u0633\u0628\u062a \u0634\u0647\u0627\u062f\u062a \u0631\u06cc\u06cc\u0633 \u062c\u0645\u0647\u0648\u0631"},"content":{"rendered":"<p>\n\u0627\u0639\u0636\u0627\u06cc \u0647\u06cc\u0626\u062a \u0645\u062f\u06cc\u0631\u0647\u060c \u0645\u062f\u06cc\u0631\u0627\u0646 \u0648 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627 \u0637\u06cc \u067e\u06cc\u0627\u0645\u06cc \u0634\u0647\u0627\u062f\u062a \u0631\u0626\u06cc\u0633 \u062c\u0645\u0647\u0648\u0631 \u0645\u0631\u062f\u0645\u06cc \u0648 \u0647\u0645\u0631\u0627\u0647\u0627\u0646\u0634\u0627\u0646 \u0631\u0627 \u062a\u0633\u0644\u06cc\u062a \u06af\u0641\u062a\u0646\u062f.<br \/>\n\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc  \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627\u061b \u0645\u062a\u0646 \u0627\u06cc\u0646 \u067e\u06cc\u0627\u0645 \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u0627\u0633\u062a:<\/p>\n<p>\u0625\u0650\u0646\u064e\u0651\u0640\u0627 \u0644\u0650\u0640\u0644\u064e\u0651\u0640\u0647\u0650 \u0648\u064e \u0625\u0650\u0646\u064e\u0651\u0640\u0627 \u0625\u0650\u0644\u064e\u0640\u06cc\u0652\u0640\u0647\u0650 \u0631\u064e\u0627\u062c\u0650\u0640\u0639\u064f\u0640\u0648\u0646\u064e<\/p>\n<p>\u062d\u0627\u062f\u062b\u0647 \u062f\u0644\u062e\u0631\u0627\u0634 \u0633\u0642\u0648\u0637 \u0628\u0627\u0644\u06af\u0631\u062f \u0648 \u0634\u0647\u0627\u062f\u062a \u062c\u0627\u0646\u06af\u062f\u0627\u0632 \u0631\u0626\u06cc\u0633 \u0645\u062d\u062a\u0631\u0645 \u062c\u0645\u0647\u0648\u0631\u060c \u0648\u0632\u06cc\u0631 \u0627\u0645\u0648\u0631 \u062e\u0627\u0631\u062c\u0647\u060c \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0648\u0644\u06cc \u0641\u0642\u06cc\u0647 \u062f\u0631 \u0622\u0630\u0631\u0628\u0627\u06cc\u062c\u0627\u0646 \u0634\u0631\u0642\u06cc\u060c \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631 \u0622\u0630\u0631\u0628\u0627\u06cc\u062c\u0627\u0646 \u0634\u0631\u0642\u06cc \u0648 \u0647\u0645\u0631\u0627\u0647\u0627\u0646\u0634\u0627\u0646 \u062f\u0631 \u0631\u0648\u0632 \u0648\u0644\u0627\u062f\u062a \u0627\u0645\u0627\u0645 \u0647\u0634\u062a\u0645 \u0634\u06cc\u0639\u06cc\u0627\u0646 \u0627\u0645\u0627\u0645 \u0631\u0636\u0627(\u0639) \u0645\u0627\u06cc\u0647 \u062a\u0623\u0633\u0641 \u0648 \u062a\u0623\u062b\u0631 \u0647\u0645\u06af\u0627\u0646 \u0634\u062f.<br \/>\n\u0627\u06cc\u0646 \u0639\u0632\u06cc\u0632\u0627\u0646 \u06a9\u0647 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062e\u062f\u0645\u062a \u0635\u0627\u062f\u0642\u0627\u0646\u0647 \u0648 \u062a\u0648\u0633\u0639\u0647 \u0647\u0631\u0686\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0647 \u0645\u06cc\u0627\u0646 \u0645\u0631\u062f\u0645 \u0634\u0631\u06cc\u0641 \u0622\u0630\u0631\u0628\u0627\u06cc\u062c\u0627\u0646 \u0634\u0631\u0642\u06cc \u0631\u0641\u062a\u0647 \u0628\u0648\u062f\u0646\u062f\u060c \u062f\u0631 \u062d\u06cc\u0646 \u062e\u062f\u0645\u062a \u0628\u0647 \u062f\u06cc\u062f\u0627\u0631 \u062d\u0642 \u062a\u0639\u0627\u0644\u06cc \u0634\u062a\u0627\u0641\u062a\u0646\u062f.<br \/>\n\u0634\u0631\u06a9\u062a \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627\u060c \u0627\u06cc\u0646 \u0636\u0627\u06cc\u0639\u0647 \u062f\u0631\u062f\u0646\u0627\u06a9 \u0631\u0627 \u0645\u062d\u0636\u0631 \u0645\u0642\u0627\u0645 \u0645\u0639\u0638\u0645 \u0631\u0647\u0628\u0631\u06cc \u062d\u0636\u0631\u062a \u0622\u06cc\u062a \u0627\u0644\u0644\u0647 \u062e\u0627\u0645\u0646\u0647\u200c\u0627\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0644\u062a \u0634\u0631\u06cc\u0641 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0633\u0644\u0627\u0645\u06cc \u062a\u0633\u0644\u06cc\u062a \u0639\u0631\u0636 \u0646\u0645\u0648\u062f\u0647 \u0648 \u0628\u0631\u0627\u06cc \u0631\u0648\u062d \u0628\u0644\u0646\u062f \u0627\u06cc\u0646 \u0634\u0647\u062f\u0627\u06cc \u0648\u0627\u0644\u0627\u0645\u0642\u0627\u0645\u060c \u0631\u062d\u0645\u062a \u0648 \u0645\u063a\u0641\u0631\u062a \u0627\u0644\u0647\u06cc \u0648 \u0639\u0644\u0648\u0651 \u062f\u0631\u062c\u0627\u062a \u0627\u0632 \u062e\u062f\u0627\u0648\u0646\u062f \u0645\u062a\u0639\u0627\u0644 \u0631\u0627 \u0645\u0633\u0623\u0644\u062a \u062f\u0627\u0631\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0639\u0636\u0627\u06cc \u0647\u06cc\u0626\u062a \u0645\u062f\u06cc\u0631\u0647\u060c \u0645\u062f\u06cc\u0631\u0627\u0646 \u0648 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627 \u0637\u06cc \u067e\u06cc\u0627\u0645\u06cc \u0634\u0647\u0627\u062f\u062a \u0631\u0626\u06cc\u0633 \u062c\u0645\u0647\u0648\u0631 \u0645\u0631\u062f\u0645\u06cc \u0648 \u0647\u0645\u0631\u0627\u0647\u0627\u0646\u0634\u0627\u0646 \u0631\u0627 \u062a\u0633\u0644\u06cc\u062a \u06af\u0641\u062a\u0646\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637 \u0639\u0645\u0648\u0645\u06cc \u0628\u06cc\u0645\u0647 \u0633\u06cc\u0646\u0627\u061b \u0645\u062a\u0646 \u0627\u06cc\u0646 \u067e\u06cc\u0627\u0645 \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u0627\u0633\u062a: \u0625\u0650\u0646\u064e\u0651\u0640\u0627 \u0644\u0650\u0640\u0644\u064e\u0651\u0640\u0647\u0650 \u0648\u064e \u0625\u0650\u0646\u064e\u0651\u0640\u0627 \u0625\u0650\u0644\u064e\u0640\u06cc\u0652\u0640\u0647\u0650 \u0631\u064e\u0627\u062c\u0650\u0640\u0639\u064f\u0640\u0648\u0646\u064e \u062d\u0627\u062f\u062b\u0647 \u062f\u0644\u062e\u0631\u0627\u0634 \u0633\u0642\u0648\u0637 \u0628\u0627\u0644\u06af\u0631\u062f \u0648 \u0634\u0647\u0627\u062f\u062a \u062c\u0627\u0646\u06af\u062f\u0627\u0632 \u0631\u0626\u06cc\u0633 \u0645\u062d\u062a\u0631\u0645 \u062c\u0645\u0647\u0648\u0631\u060c \u0648\u0632\u06cc\u0631 \u0627\u0645\u0648\u0631 \u062e\u0627\u0631\u062c\u0647\u060c [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":118078,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-118077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-18"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/118077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=118077"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/118077\/revisions"}],"predecessor-version":[{"id":118079,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/118077\/revisions\/118079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/118078"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=118077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=118077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=118077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}