{"id":113105,"date":"2023-10-29T07:13:45","date_gmt":"2023-10-29T08:13:45","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=113105"},"modified":"2023-10-29T07:13:45","modified_gmt":"2023-10-29T08:13:45","slug":"%d8%a8%d8%b1%da%af%d8%b2%d8%a7%d8%b1%db%8c-%d8%a7%d9%88%d9%84%db%8c%d9%86-%d8%ac%d8%b4%d9%86%d9%88%d8%a7%d8%b1%d9%87-%d9%88%d8%b1%d8%b2%d8%b4%db%8c-%da%a9%d8%a7%d8%b1%da%a9%d9%86%d8%a7%d9%86-%d9%88","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/113105","title":{"rendered":"\u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u0648\u0644\u06cc\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u0648\u0631\u0632\u0634\u06cc \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0628\u0627 \u0631\u0642\u0627\u0628\u062a \u06f3 \u0647\u0632\u0627\u0631 \u0648\u0631\u0632\u0634\u06a9\u0627\u0631"},"content":{"rendered":"<p>\u0645\u062f\u06cc\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u06af\u0631\u0648\u0647 \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0622\u063a\u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u0648\u0644\u06cc\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u0641\u0631\u0647\u0646\u06af\u06cc \u0648\u0631\u0632\u0634\u06cc \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0627\u0632 \u0634\u0647\u0631\u06cc\u0648\u0631\u0645\u0627\u0647\u060c \u06af\u0641\u062a: \u0628\u0627 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u06cc\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u06a9\u0647 \u062f\u0631 \u0686\u0646\u062f \u0645\u0631\u062d\u0644\u0647 \u0648 \u062a\u0627 \u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0634\u0627\u0647\u062f \u062a\u0642\u0648\u06cc\u062a \u0631\u0648\u062d\u06cc\u0647 \u0648 \u0646\u0634\u0627\u0637 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0648\u062f.<\/p>\n<p>\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0631\u0648\u0627\u0628\u0637\u200c\u0639\u0645\u0648\u0645\u06cc \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633\u060c \u062f\u0627\u0631\u06cc\u0648\u0634 \u0634\u0645\u0633 \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u0632 \u0627\u0628\u062a\u062f\u0627\u06cc \u0634\u0631\u0648\u0639 \u0628\u0647 \u06a9\u0627\u0631 \u0647\u0644\u062f\u06cc\u0646\u06af \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633\u060c \u062c\u0634\u0646\u0648\u0627\u0631\u0647\u200c\u0627\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0634\u06a9\u0644 \u0648 \u0627\u0628\u0639\u0627\u062f \u0628\u0631\u0627\u06cc \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0628\u0631\u06af\u0632\u0627\u0631 \u0646\u0634\u062f\u0647\u060c \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0634\u0627\u0645\u0644 \u062a\u0645\u0627\u0645 \u06af\u0631\u0648\u0647\u200c\u0647\u0627\u06cc \u0633\u0646\u06cc \u0648 \u0628\u0627 \u062a\u0639\u062f\u0627\u062f \u0642\u0627\u0628\u0644\u200c\u062a\u0648\u062c\u0647\u06cc \u0627\u0632 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u0648\u0631\u0632\u0634\u06cc \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u0648\u06cc  \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0627\u062d\u06cc\u0627\u06cc \u0634\u0648\u0631\u0627\u06cc \u0648\u0631\u0632\u0634 \u0634\u0631\u06a9\u062a\u060c \u0645\u062a\u0634\u06a9\u0644 \u0627\u0632 \u0645\u062f\u06cc\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u06af\u0631\u0648\u0647\u060c \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0648\u0631\u0632\u0634 \u0647\u0644\u062f\u06cc\u0646\u06af \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0648 \u0631\u0624\u0633\u0627\u06cc \u0648\u0631\u0632\u0634 \u0634\u0631\u06a9\u062a \u0639\u0645\u0644\u06cc\u0627\u062a \u063a\u06cc\u0631\u0635\u0646\u0639\u062a\u06cc \u0645\u0627\u0647\u0634\u0647\u0631 \u0648 \u0639\u0645\u0644\u06cc\u0627\u062a \u063a\u06cc\u0631\u0635\u0646\u0639\u062a\u06cc \u067e\u0627\u0632\u0627\u0631\u06af\u0627\u062f \u0648 \u0686\u0646\u062f \u062a\u0646 \u0627\u0632 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u0628\u0627\u062a\u062c\u0631\u0628\u0647 \u0648 \u067e\u06cc\u0634\u06a9\u0633\u0648\u062a \u0648\u0631\u0632\u0634\u06cc \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u06af\u0631\u0648\u0647\u060c \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f: \u0628\u0631\u067e\u0627\u06cc\u06cc \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u067e\u0648\u06cc\u0627\u06cc\u06cc \u0648 \u0646\u0634\u0627\u0637 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631\u06cc \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627 \u0648 \u062a\u0639\u0644\u0642 \u0633\u0627\u0632\u0645\u0627\u0646\u06cc \u0627\u062b\u0631\u06af\u0630\u0627\u0631\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<br \/>\n\u0634\u0645\u0633 \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0634\u0631\u0648\u0639 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0645\u0631\u062d\u0644\u0647 \u0627\u0648\u0644 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0647\u0645\u200c\u0632\u0645\u0627\u0646 \u0628\u0627 \u0647\u0641\u062a\u0647 \u062f\u0641\u0627\u0639 \u0645\u0642\u062f\u0633 \u0627\u0638\u0647\u0627\u0631 \u062f\u0627\u0634\u062a: \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0628\u0647 \u0634\u06a9\u0644 \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0631\u062f\u060c  \u0627\u0628\u062a\u062f\u0627 \u062f\u0631 \u0634\u0647\u0631\u06cc\u0648\u0631\u0645\u0627\u0647 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u062f\u0631 \u0633\u0637\u062d \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0628\u0627 \u062d\u0636\u0648\u0631 \u06f4\u06f0\u06f0 \u0646\u0641\u0631 \u0627\u0632 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062f\u0631 \u06f1\u06f2 \u0631\u0634\u062a\u0647 \u0648 \u0627\u0632 \u06f9 \u0634\u0631\u06a9\u062a \u062f\u0631 \u0627\u0635\u0641\u0647\u0627\u0646 \u0628\u0631\u06af\u0632\u0627\u0631 \u0634\u062f \u06a9\u0647 \u0628\u0627 \u0642\u0647\u0631\u0645\u0627\u0646\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0646\u0648\u0631\u06cc \u0628\u0647 \u067e\u0627\u06cc\u0627\u0646 \u0631\u0633\u06cc\u062f.<br \/>\n\u0648\u06cc \u0628\u0627 \u062a\u0623\u06a9\u06cc\u062f \u0628\u0631 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0628\u0627 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc\u0627\u062a \u063a\u06cc\u0631\u0635\u0646\u0639\u062a\u06cc \u0627\u0646\u062c\u0627\u0645 \u0648 \u062f\u0631 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u06a9\u0627\u0645\u0644 \u0628\u0627 \u0627\u0645\u0648\u0631 \u0648\u0631\u0632\u0634 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u0627\u0646\u200c\u0647\u0627 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u0641\u0632\u0648\u062f: \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0647\u0645\u0647 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0628\u0631\u0627\u06cc \u062d\u0636\u0648\u0631 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627 \u0648 \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u0631\u0627 \u062f\u0631 \u0641\u0636\u0627\u06cc\u06cc \u067e\u0631 \u0634\u0648\u0631 \u0648 \u0646\u0634\u0627\u0637 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u06cc\u0645.<br \/>\n\u0648\u06cc \u062a\u0635\u0631\u06cc\u062d \u06a9\u0631\u062f:  \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0647\u0645\u0633\u0631\u0627\u0646 \u0648 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u062e\u0627\u0646\u0645 \u0647\u0645 \u062f\u0631 \u06f9 \u0631\u0634\u062a\u0647 \u0648\u0631\u0632\u0634\u06cc \u0648 \u0627\u0632 \u06f8 \u0634\u0631\u06a9\u062a \u0628\u0627 \u062d\u0636\u0648\u0631 \u06f6\u06f0\u06f0 \u0646\u0641\u0631 \u062f\u0631 \u0645\u0647\u0631\u0645\u0627\u0647 \u062f\u0631 \u0634\u0647\u0631 \u0634\u06cc\u0631\u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631 \u0648 \u0628\u0627 \u0642\u0647\u0631\u0645\u0627\u0646\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0646\u062f\u0631 \u0627\u0645\u0627\u0645 \u0628\u0647 \u067e\u0627\u06cc\u0627\u0646 \u0631\u0633\u06cc\u062f.<br \/>\n\u0645\u062f\u06cc\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u06af\u0631\u0648\u0647 \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633\u060c \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc\u200c\u0647\u0627\u06cc \u0635\u0648\u0631\u062a\u200c\u06af\u0631\u0641\u062a\u0647 \u062f\u0631 \u062c\u0631\u06cc\u0627\u0646 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0628\u0631\u0627\u06cc \u062d\u0636\u0648\u0631 \u067e\u06cc\u0634\u06a9\u0633\u0648\u062a\u0627\u0646 \u0648 \u0628\u0627\u0632\u0646\u0634\u0633\u062a\u06af\u0627\u0646\u060c \u0627\u0641\u0632\u0648\u062f: \u062d\u062f\u0648\u062f \u06f6\u06f5\u06f0 \u0646\u0641\u0631 \u062f\u0631 \u06f8 \u0631\u0634\u062a\u0647 \u0648\u0631\u0632\u0634\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u062d\u0636\u0648\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a \u0648 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0622\u0628\u0627\u0646\u200c\u0645\u0627\u0647 \u062f\u0631 \u0634\u06cc\u0631\u0627\u0632 \u0648 \u0627\u0635\u0641\u0647\u0627\u0646 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u0634\u0645\u0633 \u0628\u0627 \u0627\u0639\u0644\u0627\u0645 \u0627\u06cc\u0646\u06a9\u0647 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0648\u0631\u0632\u0634\u06cc \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u062f\u0631 \u06f8 \u0631\u0634\u062a\u0647 \u0648\u0631\u0632\u0634\u06cc \u062f\u0631 \u0631\u0634\u062a\u0647\u200c\u0647\u0627\u06cc \u0648\u0627\u0644\u06cc\u0628\u0627\u0644\u060c \u0634\u0646\u0627\u060c \u062a\u06cc\u0631\u0627\u0646\u062f\u0627\u0632\u06cc\u060c \u0634\u0637\u0631\u0646\u062c\u060c \u0641\u0648\u062a\u0633\u0627\u0644\u060c \u062a\u0646\u06cc\u0633\u200c\u0631\u0648\u06cc\u200c\u0645\u06cc\u0632\u060c \u062f\u0648\u0648\u0645\u06cc\u062f\u0627\u0646\u06cc \u0627\u0632 \u06f1\u06f7 \u0634\u0631\u06a9\u062a \u0648 \u0628\u0627 \u062d\u0636\u0648\u0631 \u06f8\u06f0\u06f7 \u0646\u0641\u0631 \u0627\u0632 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u062f\u0631 \u0622\u0630\u0631\u0645\u0627\u0647 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u0641\u0632\u0648\u062f: \u062f\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u062d\u062f\u0648\u062f \u06f3 \u0647\u0632\u0627\u0631 \u0646\u0641\u0631 \u0627\u0632 \u0647\u0645\u06a9\u0627\u0631\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627 \u062f\u0631 \u06a9\u0644 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631\u0645\u062c\u0645\u0648\u0639\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u062d\u0636\u0648\u0631 \u062f\u0627\u0631\u0646\u062f. \u0645\u0627 \u0647\u0645 \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u062f\u0631 \u062a\u062c\u0631\u0628\u0647 \u0627\u0648\u0644 \u06a9\u0645\u06cc \u0648 \u06a9\u0627\u0633\u062a\u06cc\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0648 \u062f\u0631 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0628\u0639\u062f\u06cc \u0627\u0635\u0644\u0627\u062d \u06a9\u0646\u06cc\u0645.<br \/>\n\u0645\u062f\u06cc\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u06af\u0631\u0648\u0647 \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u062d\u0645\u0627\u06cc\u062a\u06cc \u06a9\u0647 \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0648 \u0645\u0639\u0627\u0648\u0646\u06cc\u0646 \u0648\u06cc \u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u06cc\u0646 \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u062f\u0627\u0634\u062a\u0647\u200c\u0627\u0646\u062f \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647  \u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0641\u0631\u0632\u0646\u062f\u0627\u0646 \u062f\u062e\u062a\u0631 \u0632\u06cc\u0631 \u06f2\u06f5 \u0633\u0627\u0644 \u0647\u0645 \u062f\u0631 \u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647  \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u062f\u06cc\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0646\u0633\u0627\u0646\u06cc \u06af\u0631\u0648\u0647 \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0622\u063a\u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u0648\u0644\u06cc\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u0641\u0631\u0647\u0646\u06af\u06cc \u0648\u0631\u0632\u0634\u06cc \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0634\u0631\u06a9\u062a \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062e\u0644\u06cc\u062c\u200c\u0641\u0627\u0631\u0633 \u0627\u0632 \u0634\u0647\u0631\u06cc\u0648\u0631\u0645\u0627\u0647\u060c \u06af\u0641\u062a: \u0628\u0627 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u06cc\u0646 \u062c\u0634\u0646\u0648\u0627\u0631\u0647 \u06a9\u0647 \u062f\u0631 \u0686\u0646\u062f \u0645\u0631\u062d\u0644\u0647 \u0648 \u062a\u0627 \u0627\u0633\u0641\u0646\u062f\u0645\u0627\u0647 \u0628\u0631\u06af\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0634\u0627\u0647\u062f \u062a\u0642\u0648\u06cc\u062a \u0631\u0648\u062d\u06cc\u0647 \u0648 \u0646\u0634\u0627\u0637 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u06a9\u0627\u0631\u06a9\u0646\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0648\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":113106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-113105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/113105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=113105"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/113105\/revisions"}],"predecessor-version":[{"id":113107,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/113105\/revisions\/113107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/113106"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=113105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=113105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=113105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}