{"id":111187,"date":"2023-08-18T21:57:18","date_gmt":"2023-08-18T21:57:18","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=111187"},"modified":"2023-08-18T21:57:18","modified_gmt":"2023-08-18T21:57:18","slug":"%d9%be%db%8c%d8%a7%d9%85-%d8%af%da%a9%d8%aa%d8%b1-%d8%a8%d9%87%d8%b2%d8%a7%d8%af-%d8%b4%db%8c%d8%b1%db%8c-%d9%85%d8%af%db%8c%d8%b1-%d8%b9%d8%a7%d9%85%d9%84-%d9%be%d8%b3%d8%aa-%d8%a8%d8%a7%d9%86-2","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/111187","title":{"rendered":"\u067e\u06cc\u0627\u0645 \u062f\u06a9\u062a\u0631 \u0628\u0647\u0632\u0627\u062f \u0634\u06cc\u0631\u06cc \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u067e\u0633\u062a \u0628\u0627\u0646\u06a9 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0647 \u0645\u0646\u0627\u0633\u0628\u062a \u0633\u0627\u0644\u0631\u0648\u0632 \u0628\u0627\u0632\u06af\u0634\u062a \u063a\u0631\u0648\u0631\u0645\u0646\u062f\u0627\u0646\u0647\u200c\u06cc \u0622\u0632\u0627\u062f\u06af\u0627\u0646 \u0628\u0647 \u0645\u06cc\u0647\u0646 \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646"},"content":{"rendered":"<p>\n\u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc :\u062f\u06a9\u062a\u0631 \u0628\u0647\u0632\u0627\u062f \u0634\u06cc\u0631\u06cc \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u067e\u0633\u062a \u0628\u0627\u0646\u06a9 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0635\u062f\u0648\u0631 \u067e\u06cc\u0627\u0645\u06cc \u0628\u06cc\u0633\u062a \u0648 \u0634\u0634\u0645 \u0645\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u0633\u0627\u0644\u0631\u0648\u0632 \u0628\u0627\u0632\u06af\u0634\u062a \u063a\u0631\u0648\u0631\u0645\u0646\u062f\u0627\u0646\u0647\u200c\u06cc \u0622\u0632\u0627\u062f\u06af\u0627\u0646 \u0633\u0631\u0628\u0644\u0646\u062f \u0633\u0631\u0632\u0645\u06cc\u0646\u200c\u0645\u0627\u0646 \u0628\u0647 \u0645\u06cc\u0647\u0646 \u0639\u0632\u06cc\u0632\u0645\u0627\u0646 \u0631\u0627 \u0628\u0647 \u067e\u06cc\u0634\u06af\u0627\u0647 \u0634\u0631\u06cc\u0641 \u0645\u0644\u062a \u0627\u06cc\u0631\u0627\u0646\u060c \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0645\u0639\u0638\u0645 \u0627\u06cc\u062b\u0627\u0631\u06af\u0631\u0627\u0646 \u0648 \u0622\u0632\u0627\u062f\u06af\u0627\u0646\u060c \u0647\u0645\u06a9\u0627\u0631\u0627\u0646\u060c \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646\u060c \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0628\u0632\u0631\u06af \u067e\u0633\u062a\u200c\u0628\u0627\u0646\u06a9\u200c\u0627\u06cc\u0631\u0627\u0646 \u062a\u0628\u0631\u06cc\u06a9 \u0639\u0631\u0636 \u0646\u0645\u0648\u062f.<\/p>\n<p>\u0645\u062a\u0646 \u067e\u06cc\u0627\u0645 \u062f\u06a9\u062a\u0631 \u0634\u06cc\u0631\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0634\u0631\u062d \u0627\u0633\u062a:<br \/>\n\u0647\u0645\u0647 \u0633\u0627\u0644\u0647 \u0628\u06cc\u0633\u062a\u0645 \u0648 \u0634\u0634\u0645 \u0645\u0631\u062f\u0627\u062f \u0645\u0627\u0647 \u06cc\u0627\u062f\u0622\u0648\u0631 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0632\u0647\u0627\u06cc \u0627\u0641\u062a\u062e\u0627\u0631\u0622\u0645\u06cc\u0632 \u0648 \u067e\u0631\u063a\u0631\u0648\u0631 \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u0647\u0646 \u0639\u0632\u06cc\u0632\u0645\u0627\u0646 \u0627\u06cc\u0631\u0627\u0646 \u0627\u0633\u062a. \u062e\u062c\u0633\u062a\u0647 \u0631\u0648\u0632\u06cc \u06a9\u0647 \u0633\u0644\u062d\u0634\u0648\u0631\u0627\u0646 \u062c\u0627\u0646 \u0628\u0631\u06a9\u0641 \u0627\u06cc\u0646 \u0633\u0631\u0632\u0645\u06cc\u0646 \u0633\u0631\u0648\u062f \u0633\u0631\u0641\u0631\u0627\u0632\u06cc \u0633\u0631 \u062f\u0627\u062f\u0646\u062f \u062a\u0627 \u0628\u0646\u06cc\u0627\u0646 \u0627\u06cc\u0646 \u0645\u0631\u0632 \u0648 \u0628\u0648\u0645 \u062f\u0631 \u0633\u0627\u06cc\u0647\u200c\u06cc \u0627\u0642\u062a\u062f\u0627\u0631 \u0648 \u067e\u0627\u06cc\u0645\u0631\u062f\u06cc\u200c\u0634\u0627\u0646 \u0627\u0633\u062a\u0648\u0627\u0631 \u0648 \u067e\u0627\u0628\u0631\u062c\u0627 \u0628\u0645\u0627\u0646\u062f \u0648 \u062e\u0627\u0637\u0631\u0647\u200c\u06cc \u0631\u0646\u062c \u0627\u0633\u0627\u0631\u062a\u200c\u0634\u0627\u0646 \u067e\u0634\u062a\u0648\u0627\u0646\u0647\u200c\u06cc \u0647\u0648\u06cc\u062a \u0645\u0644\u06cc \u0645\u06cc\u0647\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646\u200c\u0645\u0627\u0646 \u0628\u0627\u0634\u062f.<br \/>\n\u0636\u0645\u0646 \u06af\u0631\u0627\u0645\u06cc\u062f\u0627\u0634\u062a \u06cc\u0627\u062f \u062e\u0627\u0637\u0631\u0647\u200c\u06cc \u0647\u0645\u0647 \u0631\u0632\u0645\u0646\u062f\u06af\u0627\u0646 \u0647\u0634\u062a \u0633\u0627\u0644 \u062f\u0641\u0627\u0639 \u0645\u0642\u062f\u0633\u060c \u0628\u06cc\u0633\u062a \u0648 \u0634\u0634\u0645 \u0645\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u0633\u0627\u0644\u0631\u0648\u0632 \u0628\u0627\u0632\u06af\u0634\u062a \u063a\u0631\u0648\u0631\u0645\u0646\u062f\u0627\u0646\u0647\u200c\u06cc \u0622\u0632\u0627\u062f\u06af\u0627\u0646 \u0633\u0631\u0628\u0644\u0646\u062f \u0633\u0631\u0632\u0645\u06cc\u0646\u200c\u0645\u0627\u0646 \u0631\u0627 \u0628\u0647 \u067e\u06cc\u0634\u06af\u0627\u0647 \u0634\u0631\u06cc\u0641 \u0645\u0644\u062a \u0627\u06cc\u0631\u0627\u0646\u060c \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0645\u0639\u0638\u0645 \u0627\u06cc\u062b\u0627\u0631\u06af\u0631\u0627\u0646 \u0648 \u0622\u0632\u0627\u062f\u06af\u0627\u0646\u060c \u0647\u0645\u06a9\u0627\u0631\u0627\u0646\u060c \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646\u060c \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0628\u0632\u0631\u06af \u067e\u0633\u062a\u200c\u0628\u0627\u0646\u06a9\u200c\u0627\u06cc\u0631\u0627\u0646 \u062a\u0628\u0631\u06cc\u06a9 \u0639\u0631\u0636 \u06a9\u0631\u062f\u0647 \u0648 \u067e\u06cc\u0631\u0648\u0632\u06cc \u0648 \u0633\u0631\u0641\u0631\u0627\u0632\u06cc \u0647\u0645\u06af\u0627\u0646 \u0631\u0627 \u0627\u0632 \u062f\u0631\u06af\u0627\u0647 \u0627\u06cc\u0632\u062f \u0645\u0646\u0627\u0646 \u062e\u0648\u0627\u0647\u0627\u0646\u06cc\u0645.<br \/>\n\u0628\u0647\u0632\u0627\u062f \u0634\u06cc\u0631\u06cc<br \/>\n\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u067e\u0633\u062a \u0628\u0627\u0646\u06a9 \u0627\u06cc\u0631\u0627\u0646<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc :\u062f\u06a9\u062a\u0631 \u0628\u0647\u0632\u0627\u062f \u0634\u06cc\u0631\u06cc \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u067e\u0633\u062a \u0628\u0627\u0646\u06a9 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u0635\u062f\u0648\u0631 \u067e\u06cc\u0627\u0645\u06cc \u0628\u06cc\u0633\u062a \u0648 \u0634\u0634\u0645 \u0645\u0631\u062f\u0627\u062f\u0645\u0627\u0647 \u0633\u0627\u0644\u0631\u0648\u0632 \u0628\u0627\u0632\u06af\u0634\u062a \u063a\u0631\u0648\u0631\u0645\u0646\u062f\u0627\u0646\u0647\u200c\u06cc \u0622\u0632\u0627\u062f\u06af\u0627\u0646 \u0633\u0631\u0628\u0644\u0646\u062f \u0633\u0631\u0632\u0645\u06cc\u0646\u200c\u0645\u0627\u0646 \u0628\u0647 \u0645\u06cc\u0647\u0646 \u0639\u0632\u06cc\u0632\u0645\u0627\u0646 \u0631\u0627 \u0628\u0647 \u067e\u06cc\u0634\u06af\u0627\u0647 \u0634\u0631\u06cc\u0641 \u0645\u0644\u062a \u0627\u06cc\u0631\u0627\u0646\u060c \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0645\u0639\u0638\u0645 \u0627\u06cc\u062b\u0627\u0631\u06af\u0631\u0627\u0646 \u0648 \u0622\u0632\u0627\u062f\u06af\u0627\u0646\u060c \u0647\u0645\u06a9\u0627\u0631\u0627\u0646\u060c \u0633\u0647\u0627\u0645\u062f\u0627\u0631\u0627\u0646\u060c \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0648 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0628\u0632\u0631\u06af \u067e\u0633\u062a\u200c\u0628\u0627\u0646\u06a9\u200c\u0627\u06cc\u0631\u0627\u0646 \u062a\u0628\u0631\u06cc\u06a9 \u0639\u0631\u0636 \u0646\u0645\u0648\u062f. \u0645\u062a\u0646 \u067e\u06cc\u0627\u0645 \u062f\u06a9\u062a\u0631 \u0634\u06cc\u0631\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0634\u0631\u062d \u0627\u0633\u062a: \u0647\u0645\u0647 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":111188,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-111187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/111187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=111187"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/111187\/revisions"}],"predecessor-version":[{"id":111189,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/111187\/revisions\/111189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/111188"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=111187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=111187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=111187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}