{"id":106126,"date":"2023-05-02T17:34:03","date_gmt":"2023-05-02T17:34:03","guid":{"rendered":"http:\/\/eghtesadtalaei.ir\/fa\/?p=106126"},"modified":"2023-05-05T17:35:06","modified_gmt":"2023-05-05T17:35:06","slug":"%d9%85%d8%b9%d8%a7%d9%88%d9%86-%d9%88%d8%b2%db%8c%d8%b1-%d9%86%d9%81%d8%aa-%d9%88-%d9%85%d8%af%db%8c%d8%b1%d8%b9%d8%a7%d9%85%d9%84-%d8%b4%d8%b1%da%a9%d8%aa-%d9%85%d9%84%db%8c-%d8%b5%d9%86%d8%a7-9","status":"publish","type":"post","link":"https:\/\/eghtesadtalaei.ir\/fa\/id\/106126","title":{"rendered":"\u0645\u0639\u0627\u0648\u0646 \u0648\u0632\u06cc\u0631 \u0646\u0641\u062a \u0648 \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc : \u0647\u0645\u0627\u06cc\u0634 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0641\u0631\u0635\u062a\u06cc \u0628\u0631\u0627\u06cc \u062a\u062c\u0647\u06cc\u0632 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u0633\u062a"},"content":{"rendered":"<p>\n\u0645\u0639\u0627\u0648\u0646 \u0648\u0632\u06cc\u0631 \u0646\u0641\u062a \u0648 \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0647\u0645\u0627\u06cc\u0634 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 IPF \u0641\u0631\u0635\u062a\u06cc \u0628\u0631\u0627\u06cc \u062a\u062c\u0647\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0627\u0633\u062a\u060c \u06af\u0641\u062a: \u0627\u0632 \u0647\u0645\u0647 \u0645\u0631\u0627\u06a9\u0632 \u0639\u0644\u0645\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0648\u0645\u06cc\u200c\u0634\u062f\u0646 \u0648 \u062f\u0633\u062a\u200c\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062a\u0627\u0632\u0647\u200c\u062a\u0631\u06cc\u0646 \u06cc\u0627\u0641\u062a\u0647\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062a\u062e\u0635\u0635\u06cc \u06cc\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f.<br \/>\n\u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 \u0646\u0642\u0644 \u0627\u0632 \u0646\u06cc\u067e\u0646\u0627\u060c \u0645\u0631\u062a\u0636\u06cc \u0634\u0627\u0647\u0645\u06cc\u0631\u0632\u0627\u06cc\u06cc \u0627\u0645\u0631\u0648\u0632 (\u0633\u0647\u200c\u0634\u0646\u0628\u0647\u060c \u062f\u0648\u0627\u0632\u062f\u0647\u0645 \u0627\u0631\u062f\u06cc\u0628\u0647\u0634\u062a\u200c\u0645\u0627\u0647) \u062f\u0631 \u0622\u06cc\u06cc\u0646 \u0627\u062e\u062a\u062a\u0627\u0645\u06cc\u0647 \u0647\u0645\u0627\u06cc\u0634 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u06af\u0631\u0627\u0645\u06cc \u062f\u0627\u0634\u062a 11 \u0627\u0631\u062f\u06cc\u0628\u0647\u0634\u062a \u0631\u0648\u0632 \u06a9\u0627\u0631\u06af\u0631\u060c \u0641\u0631\u0627\u0631\u0633\u06cc\u062f\u0646 \u0631\u0648\u0632 \u0645\u0639\u0644\u0645 \u0631\u0627 \u062a\u0628\u0631\u06cc\u06a9 \u06af\u0641\u062a.<\/p>\n<p>\u0648\u06cc \u0628\u0627 \u0627\u0634\u0627\u0631\u0647 \u0628\u0647 \u0627\u06cc\u0646\u06a9\u0647 \u0647\u0645\u0627\u06cc\u0634 IPF \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0627\u0631\u0627\u0626\u0647 \u062f\u0633\u062a\u0627\u0648\u0631\u062f\u0647\u0627 \u0648 \u062a\u0627\u0632\u0647\u200c\u0647\u0627\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0631\u0627\u06cc \u0627\u062f\u0627\u0645\u0647 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u0635\u0646\u0639\u062a \u0628\u0631\u06af\u0632\u0627\u0631 \u0634\u062f\u060c \u0627\u0638\u0647\u0627\u0631 \u06a9\u0631\u062f: \u0627\u0632 \u0647\u0645\u0647 \u062f\u0633\u062a\u200c\u0627\u0646\u062f \u06a9\u0627\u0631\u0627\u0646 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u0627\u06cc\u0646 \u0631\u0648\u06cc\u062f\u0627\u062f \u0627\u0631\u0632\u0634\u0645\u0646\u062f \u062a\u0642\u062f\u06cc\u0631 \u0648 \u0642\u062f\u0631\u062f\u0627\u0646\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0645.<br \/>\n\u0648\u06cc \u0627\u0641\u0632\u0648\u062f: \u0627\u06cc\u0646 \u0647\u0645\u0627\u06cc\u0634 \u062d\u062a\u0645\u0627 \u0622\u0633\u06cc\u0628\u200c\u0634\u0646\u0627\u0633\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0646\u0642\u0635\u200c\u0647\u0627 \u0648 \u0627\u0642\u062f\u0627\u0645\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u0647\u0631\u0686\u0647\u200c\u0628\u0647\u062a\u0631 \u0628\u0631\u06af\u0632\u0627\u0631 \u0634\u062f\u0646 \u0627\u06cc\u0646 \u0647\u0645\u0627\u06cc\u0634 \u062f\u0631\u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u062a\u06cc \u0628\u0631\u0631\u0633\u06cc \u0634\u0648\u062f.<br \/>\n\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0647\u0645\u0627\u06cc\u0634 \u0641\u0631\u0635\u062a\u06cc \u0628\u0631\u0627\u06cc \u062a\u062c\u0647\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f: \u0635\u0646\u0639\u062a\u06cc \u0628\u0647 \u06af\u0633\u062a\u0631\u062f\u06af\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0627 \u0627\u06cc\u0646 \u0633\u0637\u062d \u0627\u0632 \u067e\u06cc\u0686\u06cc\u062f\u06af\u06cc \u062f\u0627\u0646\u0634 \u0648 \u0641\u0646\u0627\u0648\u0631\u06cc \u0646\u062f\u0627\u0631\u06cc\u0645. \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0628\u0627 \u06af\u0633\u062a\u0631\u062f\u06af\u06cc \u0648\u0633\u06cc\u0639 \u062c\u063a\u0631\u0627\u0641\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0632\u0645\u06cc\u0646\u0647 \u0627\u0634\u062a\u063a\u0627\u0644 \u0648 \u0627\u06cc\u062c\u0627\u062f \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u0634\u0627\u0647\u0645\u06cc\u0631\u0632\u0627\u06cc\u06cc \u062a\u0627\u06a9\u06cc\u062f \u06a9\u0631\u062f: \u0627\u0632 \u0647\u0645\u0647 \u0645\u0631\u0627\u06a9\u0632 \u0639\u0644\u0645\u06cc\u060c \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc\u060c \u067e\u0698\u0648\u0647\u0634\u06cc\u060c \u062f\u0627\u0646\u0634\u200c\u200c\u0628\u0646\u06cc\u0627\u0646 \u0648 \u0641\u0646\u0627\u0648\u0631\u0627\u0646 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0648\u0645\u06cc\u200c\u0634\u062f\u0646 \u0635\u0646\u0639\u062a \u0648 \u062f\u0633\u062a\u200c\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062a\u0627\u0632\u0647\u200c\u062a\u0631\u06cc\u0646 \u06cc\u0627\u0641\u062a\u0647\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062a\u062e\u0635\u0635\u06cc \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u06cc\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0645\u0627 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062a\u0644\u0627\u0634 \u0628\u06cc\u0634\u062a\u0631 \u0648 \u0645\u0636\u0627\u0639\u0641 \u0628\u0631\u0627\u06cc \u062c\u0628\u0631\u0627\u0646 \u06a9\u0645\u0628\u0648\u062f\u0647\u0627\u062f\u0627\u0631\u06cc\u0645 \u0648 \u0647\u0645\u200c\u0627\u06a9\u0646\u0648\u0646 \u0628\u0633\u062a\u0631 \u0628\u0631\u0627\u06cc \u062c\u0628\u0631\u0627\u0646 \u06a9\u0645\u0628\u0648\u062f\u0647\u0627 \u0622\u0645\u0627\u062f\u0647 \u0627\u0633\u062a.<br \/>\n\u0648\u06cc \u062a\u06a9\u0645\u06cc\u0644 \u0632\u0646\u062c\u06cc\u0631\u0647 \u0627\u0631\u0632\u0634 \u0631\u0627 \u0647\u062f\u0641 \u0631\u0627\u0647\u0628\u0631\u062f\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0639\u0646\u0648\u0627\u0646 \u06a9\u0631\u062f \u0648 \u06af\u0641\u062a: \u0627\u0632 \u0647\u0644\u062f\u06cc\u0646\u06af\u200c\u0647\u0627\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u06a9\u0647 \u0647\u0645\u0686\u0648\u0646 \u0647\u0644\u062f\u06cc\u0646\u06af \u062e\u0644\u06cc\u062c \u0641\u0627\u0631\u0633 \u06a9\u0647 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0627\u062c\u0631\u0627\u06cc \u067e\u0627\u0631\u06a9\u200c\u0647\u0627\u06cc \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062a\u06a9\u0645\u06cc\u0644 \u0632\u0646\u062c\u06cc\u0631\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u0628\u0647 \u0637\u0648\u0631 \u062c\u062f\u06cc\u200c\u062a\u0631 \u0648\u0627\u0631\u062f \u0639\u0645\u0644 \u0634\u0648\u0646\u062f \u0648 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0645\u062a\u062f\u0627\u062f \u0632\u0646\u062c\u06cc\u0631\u0647 \u0628\u0647 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u0639\u0644\u0627\u0645 \u06a9\u0646\u0646\u062f.<br \/>\n\u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u0641\u0632\u0648\u062f: \u0627\u0632 \u0633\u0627\u0632\u0646\u062f\u06af\u0627\u0646 \u062f\u0627\u062e\u0644\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u06a9\u0647 \u0633\u0641\u0627\u0631\u0634\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0645\u0648\u0639\u062f \u0645\u0642\u0631\u0631 \u062a\u062d\u0648\u06cc\u0644 \u062f\u0647\u0646\u062f \u062a\u0627 \u0627\u062c\u0631\u0627\u06cc \u0637\u0631\u062d\u200c\u0647\u0627\u06cc \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0627 \u062a\u0623\u062e\u06cc\u0631 \u0647\u0645\u0631\u0627\u0647 \u0646\u0628\u0627\u0634\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0639\u0627\u0648\u0646 \u0648\u0632\u06cc\u0631 \u0646\u0641\u062a \u0648 \u0645\u062f\u06cc\u0631\u0639\u0627\u0645\u0644 \u0634\u0631\u06a9\u062a \u0645\u0644\u06cc \u0635\u0646\u0627\u06cc\u0639 \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0628\u0627 \u0628\u06cc\u0627\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0647\u0645\u0627\u06cc\u0634 \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646 IPF \u0641\u0631\u0635\u062a\u06cc \u0628\u0631\u0627\u06cc \u062a\u062c\u0647\u06cc\u0632 \u06a9\u0631\u062f\u0646 \u0645\u0633\u06cc\u0631 \u062a\u0648\u0633\u0639\u0647 \u0635\u0646\u0639\u062a \u067e\u062a\u0631\u0648\u0634\u06cc\u0645\u06cc \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0627\u0633\u062a\u060c \u06af\u0641\u062a: \u0627\u0632 \u0647\u0645\u0647 \u0645\u0631\u0627\u06a9\u0632 \u0639\u0644\u0645\u06cc \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0635\u0646\u0639\u062a \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0648\u0645\u06cc\u200c\u0634\u062f\u0646 \u0648 \u062f\u0633\u062a\u200c\u06cc\u0627\u0628\u06cc \u0628\u0647 \u062a\u0627\u0632\u0647\u200c\u062a\u0631\u06cc\u0646 \u06cc\u0627\u0641\u062a\u0647\u200c\u0647\u0627\u06cc \u0641\u0646\u06cc \u0648 \u062a\u062e\u0635\u0635\u06cc \u06cc\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0627\u0642\u062a\u0635\u0627\u062f\u0637\u0644\u0627\u06cc\u06cc \u0628\u0647 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":106127,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-106126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11"],"_links":{"self":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/106126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/comments?post=106126"}],"version-history":[{"count":1,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/106126\/revisions"}],"predecessor-version":[{"id":106128,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/posts\/106126\/revisions\/106128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media\/106127"}],"wp:attachment":[{"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/media?parent=106126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/categories?post=106126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eghtesadtalaei.ir\/fa\/wp-json\/wp\/v2\/tags?post=106126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}